{"id":21248,"date":"2016-08-10T13:17:03","date_gmt":"2016-08-10T11:17:03","guid":{"rendered":"http:\/\/www.vivianefreitas.com\/fr\/?p=21248"},"modified":"2016-08-19T15:14:32","modified_gmt":"2016-08-19T13:14:32","slug":"le-lion-et-la-peur","status":"publish","type":"post","link":"https:\/\/www.vivianefreitas.com\/fr\/2016\/08\/10\/le-lion-et-la-peur\/","title":{"rendered":"le \u00ab\u00a0Lion\u00a0\u00bb et la peur"},"content":{"rendered":"<p><iframe loading=\"lazy\" title=\"T\u00e9moignage du guerrier de la tribu des Massa\u00ef - Temple de Salomon\" width=\"660\" height=\"371\" src=\"https:\/\/www.youtube.com\/embed\/CU2U2dw4_lc?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>Observez bien l\u2019attitude des membres de cette tribu:<\/p>\n<p>Ils ont avanc\u00e9 sans peur pour affronter le lion, sachant que de cela d\u00e9pendait, pas seulement la pr\u00e9servation de leur h\u00e9ritage culturel, mais surtout toute la d\u00e9fense de leur seul moyen de subsistance.<\/p>\n<p>M\u00eame s\u2019ils ont \u00e9t\u00e9 pr\u00e9par\u00e9s pendant 7 ans, c\u2019\u00e9tait l\u00e0, \u00e0 ce moment-l\u00e0, qu\u2019ils allaient prouver si r\u00e9ellement tous les enseignements et les heures d\u2019entra\u00eenement intensif allaient avoir l\u2019effet d\u00e9sir\u00e9.<\/p>\n<p>Cet exemple m\u2019a fait s\u00e9rieusement penser \u00e0 ce que Dieu nous enseigne dans Sa Parole:<\/p>\n<p>\u00abSoyez sobres, veillez. Votre adversaire, le diable, r\u00f4de comme un lion rugissant, cherchant qui il d\u00e9vorera.\u00bb (1Pierre 5:8)<\/p>\n<p>Notre \u00ablion\u00bb a un nom et il s\u2019appelle le diable; celui qui nous tente, r\u00f4de autour de nous chaque instant et qui essaye de nous \u00abd\u00e9vorer\u00bb \u00e0 travers les probl\u00e8mes, les circonstances adverses, les tentations, etc. et la seule mani\u00e8re d\u2019arriver \u00e0 se livrer de ses pi\u00e8ges, c\u2019est en le lan\u00e7ant sur lui sans peur! Confiant dans ce que nous apprenons de la Parole de Dieu, croyant qu\u2019en tout, nous sommes plus que vainqueurs par Celui qui nous a aim\u00e9s! (Ro. 8:37)<\/p>\n<p>Avez-vous remarqu\u00e9 comme le lion a \u00e9t\u00e9 intimid\u00e9 et a fui, lorsque ces hommes se sont approch\u00e9s? Le diable est ainsi: Il a peur lorsque nous n\u2019avons pas peur\u2026 Il ne peut que fuir!<\/p>\n<p>\u00abSoumettez-vous donc \u00e0 Dieu; r\u00e9sistez au diable, et il fuira loin de vous.\u00bb (Jacques 4:7)<\/p>\n<p>Mon amie, mais pour cela il est n\u00e9cessaire que votre attitude prouve, r\u00e9ellement, votre croyance. Bien s\u00fbr, cela ne signifie pas que ces hommes n\u2019ont pas eu peur de s\u2019approcher de ces lions, car en tant qu\u2019animaux sauvages, ils pouvaient \u00eatre impr\u00e9visibles. Mais ils ne sont pas permis d\u2019\u00eatre domin\u00e9s par la peur, en vue de l\u2019objectif qui les poussait. De cette mani\u00e8re, ils se sont rappel\u00e9s et ont pratiqu\u00e9 tout ce qui leur avait \u00e9t\u00e9 enseign\u00e9 pendant le temps de leur pr\u00e9paration.<\/p>\n<p>C\u2019est ainsi que cela doit se passer avec nous, en ce qui concerne tout ce que nous apprenons de Dieu et de Sa Parole. Si vous vous effrayez devant le probl\u00e8me, devant les situations difficiles, des \u00e9preuves et des tentations, quel type de foi, d\u00e9montrez-vous?! Vous prouvez juste que tous les moments d\u2019enseignement, de direction, de message, que ce soit peu ou beaucoup, n\u2019ont pas \u00e9t\u00e9 b\u00e9n\u00e9fiques pour vous, \u00e0 cause du manque de pratique d\u2019une foi intr\u00e9pide!<\/p>\n<p>Vous vous souvenez de Daniel, sa foi a men\u00e9 Dieu \u00e0 ordonner de fermer la gueule des lions? (Daniel 6:22)<\/p>\n<p>Et cela pourquoi?<\/p>\n<p>Parce qu\u2019il n\u2019avait pas peur du d\u00e9cret du roi, qui avait le pouvoir de le faire rester en vie ou de le condamner \u00e0 mort, plus encore la gueule des lions!<\/p>\n<p><strong>Cette certitude, le fait de ne pas avoir peur, nous permet d\u2019avancer, de d\u00e9velopper dans la foi et d\u2019\u00eatre honor\u00e9s par Dieu Lui-m\u00eame, afin de glorifier Son nom.<\/strong><\/p>\n<p>Qui a dit \u00e0 Daniel de ne pas se courber devant un homme? Qui l\u2019a incit\u00e9 \u00e0 rester fid\u00e8le?<\/p>\n<p>Daniel a fait, lui-m\u00eame, ses choix!<\/p>\n<p>Il a fait le choix de rester fid\u00e8le \u00e0 ses moments avec Dieu, pr\u00e9servant, par-dessus tout, sa bonne conscience. C\u2019\u00e9tait sa priorit\u00e9!<\/p>\n<p>Cette attitude qu\u2019il a eu a fait Dieu le d\u00e9livrer d\u2019une mort certaine. Mais pas seulement! Son choix a permis que le nom de Dieu soit connu dans tout le royaume de Nabuchodonosor, qui, par son propre d\u00e9cret, a ordonn\u00e9 qu\u2019ils devaient tous reconna\u00eetre le pouvoir sauveur du Dieu de Daniel! (Daniel 6:26)<\/p>\n<p>Un autre exemple: Joseph a \u00e9t\u00e9 amen\u00e9 en prison, pendant 2 ans, parce qu\u2019il a choisi de ne pas c\u00e9der \u00e0 la tentation (Gen\u00e8se 39:10-12).<br \/>\nPlus tard, il est devenu le grand gouverneur d\u2019\u00c9gypte!<\/p>\n<p>Dieu a \u00abassist\u00e9\u00bb au choix de chacun, leur donnant la r\u00e9compense due.<br \/>\nAinsi, \u00e0 chaque instant, Il nous observe nous et nos r\u00e9actions, pour \u00e9prouver si nous allons r\u00e9ellement garder et pratiquer Sa Parole.<\/p>\n<p>Et ce que je choisis r\u00e9gira ma vie, \u00e0 partir de l\u00e0. C\u2019est pourquoi, ce n\u2019est pas tout le monde qui est approuv\u00e9 devant les situations, les luttes, les probl\u00e8mes, les \u00e9preuves, les tentations\u2026<\/p>\n<p>Tout ce que Daniel et Joseph ont appris de Dieu, \u00e0 travers les enseignements de leurs anc\u00eatres, a \u00e9t\u00e9 mis \u00e0 l\u2019\u00e9preuve. C\u2019est cela qui a dict\u00e9 ce que Dieu a fait \u00e0 l\u2019int\u00e9rieur d\u2019eux et par l\u2019interm\u00e9diaire de chacun.<\/p>\n<p>Dieu observe tout ce que nous sommes et ce que nous faisons et Il n\u2019influence pas nos choix, une fois qu\u2019Il nous a d\u00e9j\u00e0 enseign\u00e9s, orient\u00e9s et nous a donn\u00e9 Sa Parole. C\u2019est \u00e0 chacun de nous d\u2019\u00e9couter et de pratiquer. D\u2019\u00eatre attentifs \u00e0 tout ce que nous avons appris et d\u2019en faire des \u0153uvres.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dieu observe tout ce que nous sommes et ce que nous faisons et Il n\u2019influence pas nos choix&#8230;<\/p>\n","protected":false},"author":4,"featured_media":21249,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[46,19],"tags":[],"class_list":["post-21248","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-foi","category-reflexion"],"better_featured_image":{"id":21249,"alt_text":"","caption":"","description":"","media_type":"image","media_details":{"width":1900,"height":748,"file":"2016\/08\/leao_medo-1900x748.jpg","sizes":{"thumbnail":{"file":"leao_medo-1900x748-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2016\/08\/leao_medo-1900x748-150x150.jpg"},"medium":{"file":"leao_medo-1900x748-300x118.jpg","width":300,"height":118,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2016\/08\/leao_medo-1900x748-300x118.jpg"},"medium_large":{"file":"leao_medo-1900x748-768x302.jpg","width":768,"height":302,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2016\/08\/leao_medo-1900x748-768x302.jpg"},"large":{"file":"leao_medo-1900x748-1024x403.jpg","width":1024,"height":403,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2016\/08\/leao_medo-1900x748-1024x403.jpg"},"mini-thumbnail":{"file":"leao_medo-1900x748-110x110.jpg","width":110,"height":110,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2016\/08\/leao_medo-1900x748-110x110.jpg"},"big-medium":{"file":"leao_medo-1900x748-320x220.jpg","width":320,"height":220,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2016\/08\/leao_medo-1900x748-320x220.jpg"},"post-thumbnail":{"file":"leao_medo-1900x748-825x325.jpg","width":825,"height":325,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2016\/08\/leao_medo-1900x748-825x325.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":21248,"source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2016\/08\/leao_medo-1900x748.jpg"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>le &quot;Lion&quot; et la peur - Blog Viviane Freitas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.vivianefreitas.com\/fr\/2016\/08\/10\/le-lion-et-la-peur\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"le &quot;Lion&quot; et la peur - Blog Viviane Freitas\" \/>\n<meta property=\"og:description\" content=\"Dieu observe tout ce que nous sommes et ce que nous faisons et Il n\u2019influence pas nos choix...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vivianefreitas.com\/fr\/2016\/08\/10\/le-lion-et-la-peur\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Viviane Freitas\" \/>\n<meta property=\"article:published_time\" content=\"2016-08-10T11:17:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-08-19T13:14:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vivianefreitas.com\/fr\/files\/2016\/08\/leao_medo-1900x748.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1900\" \/>\n\t<meta property=\"og:image:height\" content=\"748\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Viviane Freitas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Viviane Freitas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.vivianefreitas.com\/fr\/2016\/08\/10\/le-lion-et-la-peur\/\",\"url\":\"https:\/\/www.vivianefreitas.com\/fr\/2016\/08\/10\/le-lion-et-la-peur\/\",\"name\":\"le \\\"Lion\\\" et la peur - Blog Viviane Freitas\",\"isPartOf\":{\"@id\":\"https:\/\/www.vivianefreitas.com\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.vivianefreitas.com\/fr\/2016\/08\/10\/le-lion-et-la-peur\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.vivianefreitas.com\/fr\/2016\/08\/10\/le-lion-et-la-peur\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2016\/08\/leao_medo-1900x748.jpg\",\"datePublished\":\"2016-08-10T11:17:03+00:00\",\"dateModified\":\"2016-08-19T13:14:32+00:00\",\"author\":{\"@id\":\"https:\/\/www.vivianefreitas.com\/fr\/#\/schema\/person\/da4a30407b47e202130ab7d6faa79cd0\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.vivianefreitas.com\/fr\/2016\/08\/10\/le-lion-et-la-peur\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.vivianefreitas.com\/fr\/2016\/08\/10\/le-lion-et-la-peur\/#primaryimage\",\"url\":\"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2016\/08\/leao_medo-1900x748.jpg\",\"contentUrl\":\"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2016\/08\/leao_medo-1900x748.jpg\",\"width\":1900,\"height\":748},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.vivianefreitas.com\/fr\/#website\",\"url\":\"https:\/\/www.vivianefreitas.com\/fr\/\",\"name\":\"Blog Viviane Freitas\",\"description\":\"Bienvenue dans mon Blog\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.vivianefreitas.com\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.vivianefreitas.com\/fr\/#\/schema\/person\/da4a30407b47e202130ab7d6faa79cd0\",\"name\":\"Viviane Freitas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.vivianefreitas.com\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/718ec4eec1bf41a80d57ad6b6a8be8ab?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/718ec4eec1bf41a80d57ad6b6a8be8ab?s=96&d=mm&r=g\",\"caption\":\"Viviane Freitas\"},\"url\":\"https:\/\/www.vivianefreitas.com\/fr\/author\/viviane-freitas\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"le \"Lion\" et la peur - Blog Viviane Freitas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.vivianefreitas.com\/fr\/2016\/08\/10\/le-lion-et-la-peur\/","og_locale":"fr_FR","og_type":"article","og_title":"le \"Lion\" et la peur - Blog Viviane Freitas","og_description":"Dieu observe tout ce que nous sommes et ce que nous faisons et Il n\u2019influence pas nos choix...","og_url":"https:\/\/www.vivianefreitas.com\/fr\/2016\/08\/10\/le-lion-et-la-peur\/","og_site_name":"Blog Viviane Freitas","article_published_time":"2016-08-10T11:17:03+00:00","article_modified_time":"2016-08-19T13:14:32+00:00","og_image":[{"width":1900,"height":748,"url":"https:\/\/www.vivianefreitas.com\/fr\/files\/2016\/08\/leao_medo-1900x748.jpg","type":"image\/jpeg"}],"author":"Viviane Freitas","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Viviane Freitas","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.vivianefreitas.com\/fr\/2016\/08\/10\/le-lion-et-la-peur\/","url":"https:\/\/www.vivianefreitas.com\/fr\/2016\/08\/10\/le-lion-et-la-peur\/","name":"le \"Lion\" et la peur - Blog Viviane Freitas","isPartOf":{"@id":"https:\/\/www.vivianefreitas.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vivianefreitas.com\/fr\/2016\/08\/10\/le-lion-et-la-peur\/#primaryimage"},"image":{"@id":"https:\/\/www.vivianefreitas.com\/fr\/2016\/08\/10\/le-lion-et-la-peur\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2016\/08\/leao_medo-1900x748.jpg","datePublished":"2016-08-10T11:17:03+00:00","dateModified":"2016-08-19T13:14:32+00:00","author":{"@id":"https:\/\/www.vivianefreitas.com\/fr\/#\/schema\/person\/da4a30407b47e202130ab7d6faa79cd0"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vivianefreitas.com\/fr\/2016\/08\/10\/le-lion-et-la-peur\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vivianefreitas.com\/fr\/2016\/08\/10\/le-lion-et-la-peur\/#primaryimage","url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2016\/08\/leao_medo-1900x748.jpg","contentUrl":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2016\/08\/leao_medo-1900x748.jpg","width":1900,"height":748},{"@type":"WebSite","@id":"https:\/\/www.vivianefreitas.com\/fr\/#website","url":"https:\/\/www.vivianefreitas.com\/fr\/","name":"Blog Viviane Freitas","description":"Bienvenue dans mon Blog","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vivianefreitas.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.vivianefreitas.com\/fr\/#\/schema\/person\/da4a30407b47e202130ab7d6faa79cd0","name":"Viviane Freitas","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vivianefreitas.com\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/718ec4eec1bf41a80d57ad6b6a8be8ab?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/718ec4eec1bf41a80d57ad6b6a8be8ab?s=96&d=mm&r=g","caption":"Viviane Freitas"},"url":"https:\/\/www.vivianefreitas.com\/fr\/author\/viviane-freitas\/"}]}},"jetpack_featured_media_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2016\/08\/leao_medo-1900x748.jpg","_links":{"self":[{"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/posts\/21248","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/comments?post=21248"}],"version-history":[{"count":4,"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/posts\/21248\/revisions"}],"predecessor-version":[{"id":21253,"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/posts\/21248\/revisions\/21253"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/media\/21249"}],"wp:attachment":[{"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/media?parent=21248"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/categories?post=21248"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/tags?post=21248"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}