{"id":20174,"date":"2015-10-06T10:21:56","date_gmt":"2015-10-06T10:21:56","guid":{"rendered":"http:\/\/www.vivianefreitas.com\/fr\/?p=20174"},"modified":"2015-10-06T10:21:56","modified_gmt":"2015-10-06T10:21:56","slug":"17eme-jour-comment-dois-je-penser","status":"publish","type":"post","link":"https:\/\/www.vivianefreitas.com\/fr\/2015\/10\/06\/17eme-jour-comment-dois-je-penser\/","title":{"rendered":"17\u00e8me  Jour: Comment dois-je penser?"},"content":{"rendered":"<p>Salut \u00e0 tous les internautes, nous sommes d\u00e9j\u00e0 au 17\u00e8me jour du je\u00fbne.<\/p>\n<p>Ce je\u00fbne, il est glorieux pour moi, le savez-vous pourquoi ?<\/p>\n<p>\u00c9tant donn\u00e9 que je suis en train de lire vos commentaires, je me sens proche de vous et aussi, par le fait de penser aux choses de Dieu, il n\u2019y a pas meilleure chose, n\u2019est-ce pas?!<\/p>\n<p>Notre foi est raviv\u00e9e, il n\u2019y a pas de place pour les doutes, les peurs, les ins\u00e9curit\u00e9s, les blessures\u2026 Il y a un changement dans notre proc\u00e9d\u00e9, dans notre fa\u00e7on d\u2019\u00eatre, de penser\u2026<\/p>\n<p>Bien !<\/p>\n<p>Aujourd\u2019hui, profitons pour continuer \u00e0 parler, au sujet de la pens\u00e9e, j\u2019aimerai parler ici, sur le blog : <em>\u00ab Comment dois-je penser ? \u00bb<\/em><\/p>\n<p>Hier, nous avons parler de la pens\u00e9e impie&#8230; qu\u2019\u00eates vous en train de cogiter ?<\/p>\n<p>Aujourd\u2019hui, nous parlerons de la fa\u00e7on, dont nous devons penser, accompagnez-moi dans le livre de Philippiens, chapitre 4, du verset 8 au 9.<\/p>\n<blockquote><p>\u00ab Au reste, fr\u00e8res, que tout ce qui est vrai, tout ce qui est honorable, tout ce qui est juste, tout ce qui est pur, tout ce qui est aimable, tout ce qui m\u00e9rite l&rsquo;approbation, ce qui est vertueux et digne de louange, soit l&rsquo;objet de vos pens\u00e9es.<br \/>\nCe que vous avez appris, re\u00e7u et entendu de moi, et ce que vous avez vu en moi, pratiquez-le. Et le Dieu de paix sera avec vous. \u00bb<\/p><\/blockquote>\n<p>J\u2019ai beaucoup \u00e0 dire, en plus, pendant que je lisais ce passage, on dirait, que j\u2019entendais la voix de maman, parlant avec moi. Elle est si belle, ma m\u00e8re.<\/p>\n<p>R\u00e9fl\u00e9chissons au sujet de \u00ab penser \u00bb. <strong>Qu\u2019est-ce r\u00e9fl\u00e9chir ?<\/strong><\/p>\n<p>Tout d\u2019abord, je veux vous exposer la situation dont vous \u00eates en train de vivre.<\/p>\n<p>Je lisais l\u2019un de vos commentaires, je ne me souviens pas le jour exacte, il y a quelques jours en arri\u00e8re\u2026 Une personne a mentionn\u00e9 qu\u2019elle \u00e9tait d\u00e9sesp\u00e9r\u00e9e dans sa vie \u00e9conomique, elle participe de ce je\u00fbne, mais elle ne sait pas quoi faire, elle a plusieurs dettes, et elle ne sait pas comment sera son lendemain\u2026<\/p>\n<p>Lorsque j\u2019ai lu, j\u2019ai eu le c\u0153ur serr\u00e9, je me suis couch\u00e9 en train de penser \u00e0 cela. Et j\u2019ai eu mal, mais, \u00e9tant donn\u00e9, que je lis plusieurs commentaires, j\u2019ai eu envie de parler \u00e0 plusieurs personnes en m\u00eame temps, mais il faut avoir du temps, et malheureusement ce n\u2019est pas possible.<\/p>\n<p>Mais profitant de cette opportunit\u00e9, j\u2019aimerai parler \u00e0 vous qui vivez un moment tr\u00e8s difficile.<\/p>\n<p>Cette personne a m\u00eame comment\u00e9 au sujet de la crise mondial, et voil\u00e0 les pens\u00e9s qui arrivent, ce-sont de pens\u00e9es de crainte.<\/p>\n<p>Vous pensez \u00e0 ce que vous vivez, \u00e0 la situation, bien s\u00fbr que, lorsque nous pensons aux probl\u00e8mes, il arrive une tristesse, celle-ci n\u2019est pas amie avec la foi, c&rsquo;est l\u2019oppos\u00e9, c\u2019est un sentiment ennemie de la foi.<\/p>\n<p><strong>Alors, comment devons-nous vivre en Esprit ?<\/strong><\/p>\n<p>Ici, il est \u00e9crit, que tout ce qui est vrai, \u00e0 savoir la parole de Dieu, le doute est un mensonge, donc le doute ne croit pas \u00e0 ce qui est \u00e9crit dans la parole de Dieu.<\/p>\n<p>La peur aussi, lorsque j\u2019ai peur, je suis en train de douter, que Dieu fera ce que je ne peux pas faire.<\/p>\n<p>Il y a quelques jours en arri\u00e8re, o\u00f9 il y avait une situation dans ma vie, et je mentionnais le probl\u00e8me, \u00e0 chaque foi : \u00ab ah, ceci est d\u00fb \u00e0 ceci, cela\u2026 vous devez comprendre \u00e0 cause de ceci, cela\u2026\u00bb, comme si j\u2019\u00e9tais en train de nourrir, et vraiment je l\u2019\u00e9tais, nourrir un doute, une peur, enfin, un mensonge du diable.<\/p>\n<p style=\"text-align: center;\"><strong>La parole de Dieu est v\u00e9ritable, et si je crois en elle, le probl\u00e8me qui est l\u00e0 disparaitra.<\/strong><\/p>\n<p>L\u2019exemple de cette personne, qu\u2019affronte un probl\u00e8me financier terrible\u2026 il est difficile pour elle, de r\u00e9fl\u00e9chir, de se lancer dans ce je\u00fbne, et en plus de cela, le diable aime enlever nos forces, en nous faisant voir les probl\u00e8mes. Cela enl\u00e8ve nos forces.<\/p>\n<p>Alors, voyons dans la parole de Dieu, qui est v\u00e9ritable. Les paroles du diable, tels que: \u00ab Et la dette ? \u00bb La dette ou le probl\u00e8me, seront r\u00e9solues!<\/p>\n<p>Comment ? Me demandez-vous.<\/p>\n<p>En utilisant ma foi :<em> \u00ab Mon Dieu, je veux que le Seigneur m\u2019inspire. Je ne veux pas d\u00e9vier de mon objectif, d\u2019\u00eatre Un avec le Seigneur, parce que si j\u2019ai un probl\u00e8me financier, et je ne vois pas l\u2019issue, c\u2019est parce que je suis en train de vivre dans la chair, dans le sentiment, avec la peur, inqui\u00e8te\u2026 \u00bb<\/em><\/p>\n<p>Ceci, ne peut pas arriver !<\/p>\n<p>Ceci, ce n\u2019est pas vivre selon la foi, et si vous n\u2019\u00eates pas exauc\u00e9 dans vos pri\u00e8res, c\u2019est parce que cette pri\u00e8re l\u00e0, faite avec peur\u2026 Dieu n\u2019\u00e9coute pas, Il \u00e9coute et exauce la foi.<\/p>\n<p>Et vous entendez tellement, l\u2019\u00e9v\u00eaque Macedo parler \u00e0 ce sujet.<\/p>\n<p>Pensez \u00e0 ce qui est vrai, c\u2019est-\u00e0-dire, \u00e0 la parole de Dieu. Qu\u2019elle est votre situation ? Vous avez peur, vous \u00eates timides, vous avez des blessures\u2026 alors, vous allez voir qu\u2019elle est votre situation et vous allez la r\u00e9soudre, vous ne pouvez pas cacher la v\u00e9rit\u00e9, peut-\u00eatre vous dites : \u00ab j\u2019ai d\u00e9j\u00e0 tout fait\u2026 j\u2019ai particip\u00e9 dans les campagnes d\u2019Isra\u00ebl, des propos\u2026 je ne sais plus quoi faire\u2026 \u00bb<\/p>\n<p>Mon amie internaute, si vous avez fait un v\u0153u au sujet de votre probl\u00e8me, pourquoi doutez-vous ? Pourquoi cela, contamine votre foi ?<\/p>\n<p>Car, lorsque nous faisons tout, il n\u2019y a pas d\u2019ins\u00e9curit\u00e9!<\/p>\n<p>Mais, lorsque nous ne faisons pas tout, il y a toujours le doute : \u00ab est-ce que c\u2019\u00e9tait le meilleur?\u2026<\/p>\n<p>Pensez \u00e0 ce qui est vrai, regardez quels sont les faits que vous \u00eates en train de vivre sur le moment et cherchez la v\u00e9rit\u00e9 dans votre vie, celle que vous \u00eates, une personne craintif, remplie de doutes, de peurs, quoi que ce soit, et en lieu de rester l\u00e0-dessus, regardez la parole de Dieu, et dites Lui: \u00ab je suis en train de pr\u00e9senter une chose, mais je veux te pr\u00e9senter ce qui est \u00e9crit;<\/p>\n<p>Et c\u2019est cela que vous devez penser, \u00e0 ce qui vrai, honorable\u2026 Peut-\u00eatre dans votre pens\u00e9, vous n\u2019\u00eates pas en train de respecter, vous pensez du mal de quelqu\u2019un, vous l\u2019insultez dans votre pens\u00e9, vous condamnez quelqu\u2019un, tout ceci n\u2019est pas honorable. Vous devez retirer cette pens\u00e9.<\/p>\n<p style=\"text-align: center;\"><strong>Lorsque, je fais une analyse de celle que je suis, du probl\u00e8me, et je r\u00e9fl\u00e9chi de fa\u00e7on intelligente, je p\u00e8se de fa\u00e7on \u00e0 savoir, si ce que je pense est vrai, honorable, juste, qu\u2019est-ce que je peux bien faire, qui n\u2019est pas juste, qui n\u2019est pas pure, aimable, qui m\u00e9rite approbation&#8230;<\/strong><\/p>\n<p>Peut-\u00eatre vous \u00eates une personne, qui a la r\u00e9putation, d\u2019\u00eatre quelqu\u2019un de sensible, o\u00f9 les autres doivent faire attention pour ne pas vous blesser, de quelqu\u2019un d\u2019explosif, de d\u00e9sesp\u00e9r\u00e9, \u00e0 qui l\u2019on donne une nouvelle et vous devenez agressif, de quelqu\u2019un nerveuse, timide, enfin, regardez la situation que vous \u00eates en train de vivre et celle que vous devriez \u00eatre.<\/p>\n<p>Je ne suis pas en train de vous dire, que vous devez regardez le probl\u00e8me et vous culpabiliser. Une jeune fille est arriv\u00e9e pr\u00e8s de moi, et m\u2019a dit qu\u2019elle ne voyait pas le besoin, qu\u2019elle a du Saint-Esprit, elle n\u2019a pas soif du Saint-Esprit. Et je lui ai dit, qu\u2019elle devrait prendre soin d\u2019elle, de re-\u00e9couter les audio des 21 jours, de recommencer de nouveau, et avancer tout doucement, \u00eatre attentive \u00e0 ce qu\u2019elle dit.<\/p>\n<p><span style=\"text-decoration: underline;\"><em>Alors, mon amie internaute, vous devez comparer, votre pens\u00e9e, car il r\u00e9v\u00e8le votre \u00eatre, votre coeur, souvenez-vous que le coeur a des pens\u00e9s.<\/em><\/span><\/p>\n<p>Cherchez \u00e0 comprendre, quel est la fa\u00e7on que vous pensez, comment vous \u00eates en train d\u2019agir avec les personnes, parce votre r\u00e9putation est li\u00e9 \u00e0 vos relations, celle que vous \u00eates envers les autres.<\/p>\n<blockquote><p>\u00ab tout ce qui m\u00e9rite l&rsquo;approbation, ce qui est vertueux et digne de louange, soit l&rsquo;objet de vos pens\u00e9es. \u00bb<\/p><\/blockquote>\n<p>C\u2019est-\u00e0-dire, si quelqu\u2019un donne un mauvais t\u00e9moignage, a un mauvais comportement, que dois-je faire? Je dois prendre garde, et voir ce qui est juste, c\u2019est d\u2019occuper ma pens\u00e9 avec le mauvais comportement ou de fa\u00e7on \u00e0 veiller sur ma proc\u00e9d\u00e9.<\/p>\n<p>S\u2019il y a une chose g\u00eanante, comme au moment o\u00f9 j\u2019ai lu le commentaire, je me suis dit, comme j\u2019aimerais r\u00e9pondre aux internautes, parce que des fois \u00e9crire n\u2019est pas suffisant, je veux parler, m\u2019exprimer, mais j&rsquo;ai dit: \u00ab mon Dieu, le Seigneur donnera la r\u00e9ponse\u2026 \u00bb, je commentais m\u00eame avec mon \u00e9poux \u00e0 ce sujet. Dieu utilisera les audio, pour r\u00e9pondre \u00e0 ces personnes.<\/p>\n<p>Ecoutez les bien. Cette audio est en train de r\u00e9pondre \u00e0 plusieurs probl\u00e8mes que vous \u00eates en train d\u2019affronter.<\/p>\n<p>Il y a aussi le fait, de se comparer, de se culpabiliser, ceci dit, que votre pens\u00e9 n\u2019est pas juste.<\/p>\n<blockquote><p>\u00ab Ce que vous avez appris, re\u00e7u et entendu de moi, et ce que vous avez vu en moi, pratiquez-le. \u00bb<\/p><\/blockquote>\n<p>En d\u2019autres thermes, ce que j\u2019ai appris, j\u2019ai re\u00e7u, j\u2019ai entendu, j\u2019ai vu, je dois pratiquer. Je ne peux pas avoir uniquement de la connaissance, je dois pratiquer.<\/p>\n<p>Voyez-vous, le doute, la peur, l\u2019inconstance, l\u2019ins\u00e9curit\u00e9, la timidit\u00e9, les conflits, les traumas, tout ceci n\u2019aboutira pas, parce que vous acceptez d\u2019apprendre, de recevoir, d\u2019entendre, de voir ce que Dieu, Il fait, comment Il est, et vous pratiquez.<\/p>\n<p>Alors, mon amie, vous aurez la paix, en lieu de l\u2019ins\u00e9curit\u00e9, de la tristesse gard\u00e9 \u00e0 l\u2019int\u00e9rieur de vous.<\/p>\n<p>Faites votre commentaire, vous qui n\u2019avez jamais \u00e9crit, j\u2019aimerai savoir plus, je veux lire.<\/p>\n<p>Je vous embrasse tr\u00e8s fort, et demain nous serons l\u00e0 de retour.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Alors, mon amie internaute, vous devez comparer, votre pens\u00e9e, car il r\u00e9v\u00e8le votre \u00eatre, votre coeur, souvenez-vous que le coeur a des pens\u00e9s.<\/p>\n","protected":false},"author":4,"featured_media":20175,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[27],"tags":[],"class_list":["post-20174","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-jeune-21-jours"],"better_featured_image":{"id":20175,"alt_text":"","caption":"","description":"","media_type":"image","media_details":{"width":1900,"height":774,"file":"2015\/10\/17dia_JD_devo_pensar.jpg","sizes":{"thumbnail":{"file":"17dia_JD_devo_pensar-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/10\/17dia_JD_devo_pensar-150x150.jpg"},"medium":{"file":"17dia_JD_devo_pensar-300x122.jpg","width":300,"height":122,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/10\/17dia_JD_devo_pensar-300x122.jpg"},"large":{"file":"17dia_JD_devo_pensar-1024x417.jpg","width":1024,"height":417,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/10\/17dia_JD_devo_pensar-1024x417.jpg"},"mini-thumbnail":{"file":"17dia_JD_devo_pensar-110x110.jpg","width":110,"height":110,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/10\/17dia_JD_devo_pensar-110x110.jpg"},"big-medium":{"file":"17dia_JD_devo_pensar-320x220.jpg","width":320,"height":220,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/10\/17dia_JD_devo_pensar-320x220.jpg"},"full-post-thumbnail":{"file":"17dia_JD_devo_pensar-1900x748.jpg","width":1900,"height":748,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/10\/17dia_JD_devo_pensar-1900x748.jpg"},"post-thumbnail":{"file":"17dia_JD_devo_pensar-825x325.jpg","width":825,"height":325,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/10\/17dia_JD_devo_pensar-825x325.jpg"}},"image_meta":{"aperture":0,"credit":"","camera":"","caption":"","created_timestamp":0,"copyright":"","focal_length":0,"iso":0,"shutter_speed":0,"title":"","orientation":0}},"post":20174,"source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/10\/17dia_JD_devo_pensar.jpg"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>17\u00e8me Jour: Comment dois-je penser? - Blog Viviane Freitas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.vivianefreitas.com\/fr\/2015\/10\/06\/17eme-jour-comment-dois-je-penser\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"17\u00e8me Jour: Comment dois-je penser? - Blog Viviane Freitas\" \/>\n<meta property=\"og:description\" content=\"Alors, mon amie internaute, vous devez comparer, votre pens\u00e9e, car il r\u00e9v\u00e8le votre \u00eatre, votre coeur, souvenez-vous que le coeur a des pens\u00e9s.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vivianefreitas.com\/fr\/2015\/10\/06\/17eme-jour-comment-dois-je-penser\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Viviane Freitas\" \/>\n<meta property=\"article:published_time\" content=\"2015-10-06T10:21:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vivianefreitas.com\/fr\/files\/2015\/10\/17dia_JD_devo_pensar.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1900\" \/>\n\t<meta property=\"og:image:height\" content=\"774\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Viviane Freitas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Viviane Freitas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.vivianefreitas.com\/fr\/2015\/10\/06\/17eme-jour-comment-dois-je-penser\/\",\"url\":\"https:\/\/www.vivianefreitas.com\/fr\/2015\/10\/06\/17eme-jour-comment-dois-je-penser\/\",\"name\":\"17\u00e8me Jour: Comment dois-je penser? - Blog Viviane Freitas\",\"isPartOf\":{\"@id\":\"https:\/\/www.vivianefreitas.com\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.vivianefreitas.com\/fr\/2015\/10\/06\/17eme-jour-comment-dois-je-penser\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.vivianefreitas.com\/fr\/2015\/10\/06\/17eme-jour-comment-dois-je-penser\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/10\/17dia_JD_devo_pensar.jpg\",\"datePublished\":\"2015-10-06T10:21:56+00:00\",\"author\":{\"@id\":\"https:\/\/www.vivianefreitas.com\/fr\/#\/schema\/person\/da4a30407b47e202130ab7d6faa79cd0\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.vivianefreitas.com\/fr\/2015\/10\/06\/17eme-jour-comment-dois-je-penser\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.vivianefreitas.com\/fr\/2015\/10\/06\/17eme-jour-comment-dois-je-penser\/#primaryimage\",\"url\":\"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/10\/17dia_JD_devo_pensar.jpg\",\"contentUrl\":\"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/10\/17dia_JD_devo_pensar.jpg\",\"width\":1900,\"height\":774},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.vivianefreitas.com\/fr\/#website\",\"url\":\"https:\/\/www.vivianefreitas.com\/fr\/\",\"name\":\"Blog Viviane Freitas\",\"description\":\"Bienvenue dans mon Blog\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.vivianefreitas.com\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.vivianefreitas.com\/fr\/#\/schema\/person\/da4a30407b47e202130ab7d6faa79cd0\",\"name\":\"Viviane Freitas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.vivianefreitas.com\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/718ec4eec1bf41a80d57ad6b6a8be8ab?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/718ec4eec1bf41a80d57ad6b6a8be8ab?s=96&d=mm&r=g\",\"caption\":\"Viviane Freitas\"},\"url\":\"https:\/\/www.vivianefreitas.com\/fr\/author\/viviane-freitas\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"17\u00e8me Jour: Comment dois-je penser? - Blog Viviane Freitas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.vivianefreitas.com\/fr\/2015\/10\/06\/17eme-jour-comment-dois-je-penser\/","og_locale":"fr_FR","og_type":"article","og_title":"17\u00e8me Jour: Comment dois-je penser? - Blog Viviane Freitas","og_description":"Alors, mon amie internaute, vous devez comparer, votre pens\u00e9e, car il r\u00e9v\u00e8le votre \u00eatre, votre coeur, souvenez-vous que le coeur a des pens\u00e9s.","og_url":"https:\/\/www.vivianefreitas.com\/fr\/2015\/10\/06\/17eme-jour-comment-dois-je-penser\/","og_site_name":"Blog Viviane Freitas","article_published_time":"2015-10-06T10:21:56+00:00","og_image":[{"width":1900,"height":774,"url":"https:\/\/www.vivianefreitas.com\/fr\/files\/2015\/10\/17dia_JD_devo_pensar.jpg","type":"image\/jpeg"}],"author":"Viviane Freitas","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Viviane Freitas","Dur\u00e9e de lecture estim\u00e9e":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.vivianefreitas.com\/fr\/2015\/10\/06\/17eme-jour-comment-dois-je-penser\/","url":"https:\/\/www.vivianefreitas.com\/fr\/2015\/10\/06\/17eme-jour-comment-dois-je-penser\/","name":"17\u00e8me Jour: Comment dois-je penser? - Blog Viviane Freitas","isPartOf":{"@id":"https:\/\/www.vivianefreitas.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vivianefreitas.com\/fr\/2015\/10\/06\/17eme-jour-comment-dois-je-penser\/#primaryimage"},"image":{"@id":"https:\/\/www.vivianefreitas.com\/fr\/2015\/10\/06\/17eme-jour-comment-dois-je-penser\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/10\/17dia_JD_devo_pensar.jpg","datePublished":"2015-10-06T10:21:56+00:00","author":{"@id":"https:\/\/www.vivianefreitas.com\/fr\/#\/schema\/person\/da4a30407b47e202130ab7d6faa79cd0"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vivianefreitas.com\/fr\/2015\/10\/06\/17eme-jour-comment-dois-je-penser\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vivianefreitas.com\/fr\/2015\/10\/06\/17eme-jour-comment-dois-je-penser\/#primaryimage","url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/10\/17dia_JD_devo_pensar.jpg","contentUrl":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/10\/17dia_JD_devo_pensar.jpg","width":1900,"height":774},{"@type":"WebSite","@id":"https:\/\/www.vivianefreitas.com\/fr\/#website","url":"https:\/\/www.vivianefreitas.com\/fr\/","name":"Blog Viviane Freitas","description":"Bienvenue dans mon Blog","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vivianefreitas.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.vivianefreitas.com\/fr\/#\/schema\/person\/da4a30407b47e202130ab7d6faa79cd0","name":"Viviane Freitas","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vivianefreitas.com\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/718ec4eec1bf41a80d57ad6b6a8be8ab?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/718ec4eec1bf41a80d57ad6b6a8be8ab?s=96&d=mm&r=g","caption":"Viviane Freitas"},"url":"https:\/\/www.vivianefreitas.com\/fr\/author\/viviane-freitas\/"}]}},"jetpack_featured_media_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/10\/17dia_JD_devo_pensar.jpg","_links":{"self":[{"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/posts\/20174","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/comments?post=20174"}],"version-history":[{"count":1,"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/posts\/20174\/revisions"}],"predecessor-version":[{"id":20176,"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/posts\/20174\/revisions\/20176"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/media\/20175"}],"wp:attachment":[{"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/media?parent=20174"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/categories?post=20174"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/tags?post=20174"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}