{"id":20154,"date":"2015-10-01T00:00:37","date_gmt":"2015-10-01T00:00:37","guid":{"rendered":"http:\/\/www.vivianefreitas.com\/fr\/?p=20154"},"modified":"2015-10-01T09:18:15","modified_gmt":"2015-10-01T09:18:15","slug":"12eme-jour-pour-dieu-quest-ce-un-coeur-pervers","status":"publish","type":"post","link":"https:\/\/www.vivianefreitas.com\/fr\/2015\/10\/01\/12eme-jour-pour-dieu-quest-ce-un-coeur-pervers\/","title":{"rendered":"12\u00e8me Jour: \u201cPour Dieu, qu&rsquo;est-ce un coeur pervers?\u201d"},"content":{"rendered":"<p>Salut \u00e0 tous les internautes.<\/p>\n<p>C&rsquo;est un plaisir d\u2019\u00eatre ici avec vous, de vous voir participer de ces 21 jours, de vivre cette foi afin d\u2019\u00eatre \u00ab Un avec Dieu \u00bb, n\u2019est-ce pas? Vous qui \u00eates en train de chercher\u2026 d\u2019\u00eatre attentive pour conna\u00eetre \u00e0 Dieu, faire Sa volont\u00e9. V\u00e9ritablement, celle qui est attentive, b\u00e9n\u00e9ficie de ces jours.<\/p>\n<p>Bon, aujourd\u2019hui nous sommes au 12\u00e8me jours, et la question est la suivante: <em>\u00ab Pour Dieu, qu&rsquo;est-ce un coeur pervers? \u00bb<\/em><\/p>\n<p>Allons d\u00e9couvrir? Accompagnez-moi dans le livre de <strong>Proverbes, chapitre 6,\u00a0verse\u00a0 14<\/strong><\/p>\n<blockquote><p>\u00ab La perversit\u00e9 est dans son c\u0153ur, il machine du mal en tout temps, il fait na\u00eetre des querelles.<br \/>\nC&rsquo;est pourquoi sa ruine viendra tout d&rsquo;un coup; il sera subitement bris\u00e9, il n&rsquo;y aura point de gu\u00e9rison.<br \/>\nIl y a six choses que hait l&rsquo;\u00c9ternel, m\u00eame sept qui lui sont en abomination:<br \/>\nLes yeux hautains, la langue fausse, les mains qui r\u00e9pandent le sang innocent,<br \/>\nLe c\u0153ur qui forme de mauvais desseins, les pieds qui se h\u00e2tent pour courir au mal,<br \/>\nLe faux t\u00e9moin qui prononce des mensonges, et celui qui s\u00e8me des querelles entre les fr\u00e8res. \u00bb<\/p><\/blockquote>\n<p>Vous avez d\u00e9j\u00e0 constat\u00e9 que le coeur pervers, en r\u00e9sument sans entrer dans les d\u00e9tails\u2026 vous voyez que la perversit\u00e9 est li\u00e9 au fait de faire du mal \u00e0 autrui.<\/p>\n<p>Lorsqu\u2019il est \u00e9crit: \u00ab il machine du mal en tout temps \u00bb, qu\u2019est-ce que c\u2019est, machiner du mal?<\/p>\n<p>Machiner du mal, c\u2019est au moment o\u00f9 vous complotez, manigancez la vengeance, c\u2019est payer le mal par le mal&#8230; vengeance. Vous \u00eates en col\u00e8re apr\u00e8s quelqu\u2019un, et alors, vous ignorez la personne, vous blessez, vous prof\u00e9rez des mots afin de offenser. Vous machinez du mal afin de blesser, comme vous l\u2019avez \u00e9t\u00e9.<\/p>\n<p>C\u2019est-\u00e0-dire, machine du mal, fait na\u00eetre des querelles\u2026 la querelle, c\u2019est lorsque il y existe une dispute, un attaque, une influence\u2026 quand vous parlez du mal de quelqu\u2019un, qu\u2019est-ce que vous faites?<\/p>\n<p>En r\u00e9alit\u00e9, vous enseign\u00e9 l\u2019autre \u00e0 regarder avec des mauvais yeux, parce que vous regardez avec des mauvais yeux. Le m\u00eame esprit qui vous fait \u00eatre en col\u00e8re, vous le transmettez \u00e0 autrui. Parfois la personne fait de la discrimination, et l\u2019autre, peut-\u00eatre ne connait m\u00eame pas la tiers personne, mais d\u00fb au fait, qu\u2019elle a parl\u00e9 d\u2019une telle fa\u00e7on, alors, elle maltraite, elle ignore.<\/p>\n<p>Le saviez-vous, que parfois, \u00e0 cause de la jalousie, de l\u2019envie, vous finissez par agir comme \u00e7a?<\/p>\n<p>Qu\u2019est-ce le mal? Lorsque l\u2019on machine du mal, que l\u2019on r\u00e9pande de querelles&#8230; tout ce qui est \u00e0 l\u2019oppos\u00e9 du bien. Tout ce qui est malheur, disgr\u00e2ce, du tort \u00e0 autrui, alors tout ce qui \u00ab fait na\u00eetre \u00bb, ceci dit, qui lance une semence de querelle, qui transmet \u00e0 autrui cet esprit de querelle.<\/p>\n<p>Alors il est \u00e9crit que sa ruine sera soudaine, tout d\u2019un coup, subitement, sera bris\u00e9 sans qu\u2019il y ait la gu\u00e9rison. C\u2019est horrible, n\u2019est-ce pas?<\/p>\n<p>Imaginez, lorsque nous sommes bris\u00e9s, il y existe la gu\u00e9rison, du pardon. Vous revenez \u00e0 Dieu, et Il vous pardonne.<\/p>\n<p>Cependant, ici, c\u2019est \u00e9crit qu\u2019il n\u2019y aura pas de gu\u00e9rison, cela veut dire, que c\u2019est tr\u00e8s grave.<\/p>\n<p>C\u2019est le cas de ces personnes, qu\u2019un jour, elles ont \u00e9t\u00e9 parmi nous&#8230; et elles ont parl\u00e9 du mal; elles ont machin\u00e9 du mal; elles ont fait de querelles; elles ont cr\u00e9\u00e9 de la division parmi l\u2019\u00e9glise; elles ont cr\u00e9\u00e9 de la division avec \u00ab la famille spirituelle \u00bb, afin de faire pareil au royaume du diable.<\/p>\n<p>Lorsqu\u2019il est devenu Satan, et dit: \u00ab moi aussi, je suis un ange tr\u00e8s pr\u00e9cieux au ciel, je suis le plus beau et lumineux parmi les lumi\u00e8res.. \u00bb je ne me souviens pas exactement, comment il est \u00e9crit. Le diable s\u2019est rempli de l\u2019orgueil, et a influenc\u00e9 avec lui la tierce partie des anges, sauf erreur, qui se sont rebell\u00e9s contre Dieu. C\u2019est-\u00e0-dire, ce m\u00eame esprit de querelle, il a \u00e9t\u00e9 transmit aux autres, et ils sont condamn\u00e9s, ils n\u2019ont plus de gu\u00e9rison.<\/p>\n<p>Observez, \u00ab qu&rsquo;il y a six choses que hait l&rsquo;\u00c9ternel, m\u00eame sept qui lui sont en abomination \u00bb :<\/p>\n<p><strong>Les yeux hautains<\/strong> &#8211; La personne, qui ne c\u00e8de pas, elle est arrogante, orgueilleuse, Il abomine cela;<br \/>\n<strong>La langue fausse<\/strong> &#8211; La personne qui dit des mensonges;<br \/>\n<strong>Les mains qui r\u00e9pandent le sang innocent<\/strong> &#8211; C\u2019est comme parler du mal de quelqu\u2019un, qui est de Dieu, vous parlez tellement du mal\u2026 Supposent que, vous parlez du mal de l\u2019\u00e9v\u00eaque Macedo \u00e0 quelqu\u2019un (qui est un homme de Dieu), \u00e0 ce moment-l\u00e0, vous \u00e9liminez la possibilit\u00e9 qu\u2019elle essaye de chercher \u00e0 Dieu \u00e0 l\u2019\u00e9glise Universelle, \u00e9tant donn\u00e9 qu\u2019elle a entendu tellement parler du mal de l\u2019\u00e9v\u00eaque, alors elle n\u2019accepte plus\u2026 ceci dit vous avez d\u00e9vers\u00e9 du sang innocent. C\u2019est-\u00e0-dire, cette personne qui ne connait pas la v\u00e9rit\u00e9, et vous l\u2019avez influenc\u00e9 d\u2019une telle mani\u00e8re, que jamais elle n\u2019aura de l\u2019espoir de trouver\u2026 m\u00eame si elle se trouve au fond du puit, elle ne cherchera pas \u00e0 l\u2019\u00e9glise Universelle, le Dieu v\u00e9ritable.<\/p>\n<p>Pardonnez-moi, vous qui \u00eates d\u2019une autre \u00e9glise, mais je vais \u00eatre tr\u00e8s sinc\u00e8re, je ne crois pas dans une autre \u00e9glise, excusez-moi. Je crois, que l\u2019\u00e9glise du Seigneur J\u00e9sus est l\u2019\u00e9glise Universelle. Et je vais \u00eatre tr\u00e8s sinc\u00e8re, je vie \u00e0 l\u2019\u00e9glise, et je vois ce qui est juste, pure, sain pour ma vie spirituelle&#8230; tout ce que j\u2019ai d\u00e9j\u00e0 v\u00e9cu \u00e0 l\u2019\u00e9glise Universelle, je n\u2019ai jamais vu de la malice, de la m\u00e9chancet\u00e9 de la part de l\u2019\u00e9v\u00eaque Macedo.<\/p>\n<p>Et si un jour, il y a eu de la m\u00e9chancet\u00e9 de la part de quelqu\u2019un, d\u2019un homme, qui se faisait passer par un homme de Dieu, c\u2019est parce qu\u2019il a tromp\u00e9, mais en aucun cas, je ne vois pas cela de la part de mon p\u00e8re, depuis mon enfance.<\/p>\n<p>Je n\u2019ai jamais vu de la pr\u00e9tention, au contraire, je vois une personne humble, toujours pr\u00eat \u00e0 servir Dieu, \u00e0 apprendre, qui a de l\u2019amour pour les \u00e2mes, qui travaille constamment pour gagner des \u00e2mes. Il n\u2019a pas de cong\u00e9, tout le temps, sa pens\u00e9 se trouve aux choses de Dieu, je me sens honor\u00e9 d\u2019avoir un leader, non seulement un p\u00e8re, mais un leader, un homme de Dieu, un v\u00e9ritable Mo\u00efse, un ap\u00f4tre, un \u00e9v\u00eaque, excusez-moi de vous le dire, mais c\u2019est la v\u00e9rit\u00e9, il est un \u00ab soigneur \u00bb de mon \u00e2me.<\/p>\n<p>Alors, lorsque quelqu\u2019un parle mal d\u2019un homme de Dieu, elle d\u00e9verse du sang innocent.<\/p>\n<p>Cependant, il existe ceux qui sont mauvais, et bien-\u00e9videmment, ceux-l\u00e0, doivent \u00eatre d\u00e9nonc\u00e9s, par amour \u00e0 Dieu et aux \u00e2mes.<\/p>\n<p>Les mains qui d\u00e9versent du sang innocent, c\u2019est aussi, ceux qui sont parmi nous et profitent de la bonne volont\u00e9 des personnes, de la sinc\u00e9rit\u00e9.<\/p>\n<p>Alors, mon ami internaute, vous n\u2019avez pas \u00e0 vous pr\u00e9occuper, ni \u00eatre sous la d\u00e9fensive avec des mauvais yeux, parce que ceux qui sont parmi nous et ont ce mauvais esprit, de d\u00e9verser du sang innocent, t\u00f4t au tard, tout sera d\u00e9voil\u00e9. Et si vous voyez quelque chose de mauvais, vous avez le droit de d\u00e9noncer et de prouver ce qu\u2019il se passe. Si c\u2019est le cas, venez vers nous, et nous aurons le plaisir de r\u00e9soudre, pas de plaisir pour la destruction, mais pour r\u00e9soudre.<\/p>\n<p>\u00c0 l\u2019\u00e9glise Universelle, nous ne prions pas sous l\u2019injustice, notre maison n\u2019est pas injuste, notre maison, c\u2019est la maison de Dieu.<\/p>\n<p>Le c\u0153ur qui forme de mauvais desseins &#8211; Vous voyez des personnes qui veulent faire le mal, parler du mal de l\u2019\u00e9glise Universelle, de la femme, de l\u2019homme de Dieu, qui essaient de diffamer de n\u2019importe quelle fa\u00e7on, afin d\u2019\u00e9viter \u00e0 d\u2019autres de connaitre la v\u00e9rit\u00e9, ainsi comme un jour, j\u2019au connu. Ces personnes qu\u2019un jours, elles ont eu le privil\u00e8ge de conna\u00eetre la v\u00e9rit\u00e9, mais elles n\u2019ont pas voulu, elles ont opt\u00e9, par ce qui est mauvais, injuste, par la porte large, qui permet faire \u00e0 sa guise\u2026 ceux-l\u00e0, s\u2019irritent pareil \u00e0 Ca\u00efn, lorsque quelqu\u2019un offre ce qui est v\u00e9ritable, juste. Pour cela, il y existe une r\u00e9volte. Attention! Parce que vous pouvez \u00eatre l\u2019un d\u2019eux. Il suffit d\u2019\u00eatre debout, pour un jour tomber, n\u2019est-ce pas? Cependant, celui qui est \u00e0 genoux, celui qui est devant la pr\u00e9sence de Dieu, en cherchant, regardant \u00e0 lui-m\u00eame, celui-l\u00e0 ne sera jamais atteint.<\/p>\n<p>les pieds qui se h\u00e2tent pour courir au mal &#8211; Ceux qui veulent faire justice avec les propres mains, qui veulent imposer ce qui doit \u00eatre fait&#8230;<\/p>\n<p>Le faux t\u00e9moin qui prononce des mensonges, et celui qui s\u00e8me des querelles entre les fr\u00e8res &#8211; c\u2019est-\u00e0-dire, des personnes qui sont parmi nous, et parlent font du comm\u00e9rage, parle du mal\u2026 ceci est abominable, son \u00e2me s\u2019abomine.<\/p>\n<p>Voyez, comment s\u2019est grave, quoi que ce soit fait de mal, contre quelqu\u2019un d\u2019autre\u2026 entre vous et quelqu\u2019un d\u2019autre\u2026<\/p>\n<p style=\"text-align: center;\"><strong>Regardez comme Dieu, Il est beau&#8230; Il a donn\u00e9 sa vie en faveur des p\u00eacheurs, Il a donn\u00e9 son propre fils, Il n\u2019a pas donn\u00e9 n\u2019importe quel ange, Il a donn\u00e9 le meilleur afin de sauver des \u00e2mes.<\/strong><\/p>\n<p>Qui \u00eates-vous? Qui suis-je, pour porter pr\u00e9judice ou faire des querelles entres les fr\u00e8res?<\/p>\n<p>Pensez-y, mon amie internaute!<\/p>\n<p>Vous qui avez de la m\u00e9chancet\u00e9, de la malice, parce qu\u2019un \u00eatre cher est sorti de l\u2019oeuvre de Dieu ou un pasteur, une ex-\u00e9pouse, qui est pass\u00e9 dans votre vie, peu importe\u2026 et vous gardez ces souvenirs, ces m\u00e9chancet\u00e9s, de ceux qui ont donn\u00e9 un mauvais t\u00e9moignage, et ceci c\u2019est la raison pour laquelle vous ne vous lancez pas entre les mains de Dieu, corps, \u00e2me et esprit. Vous retenez toujours, avec peur que l\u2019on se profite de votre r\u00e9demption.<\/p>\n<p><strong>Non! N\u2019ayez pas peur.<\/strong> Ceux qui ont donn\u00e9 un mauvais t\u00e9moignage vont payer un prix \u00e9lev\u00e9, dans cette vie! Et ceux qui sont justes, Dieu les justifient, Dieu montre, Il r\u00e9v\u00e8le.<\/p>\n<p>Par les fruits, nous connaissons l\u2019arbre. Vous verrez par les fruits, qui est cette arbre! Bonne ou mauvaise.<\/p>\n<p>Vous choisissez, amie internaute.<\/p>\n<p>Vous choisissez dans ces 21 jours, qui voulez-vous \u00eatre, qui vous optez d\u2019\u00eatre.<\/p>\n<p>Alors, laissez ici, votre commentaire, ce que vous d\u00e9sirez parler&#8230; si c\u2019est une plainte, vous devez aller vers le pasteur, vers le responsable, afin qui pourra prendre des r\u00e9solutions \u00e0 ce sujet.<\/p>\n<p>N\u2019h\u00e9sitez pas!<\/p>\n<p>Cherchez ce qui est bon.<\/p>\n<p>Qu\u2019est-ce bon? Garder l\u2019\u00e9glise du Seigneur J\u00e9sus, n\u2019est-ce pas?<\/p>\n<p>Qu\u2019est-ce bon? Regarder avec des bons yeux.<\/p>\n<p>Qu\u2019est-ce bon? Garder et maintenir votre salut. <strong>Si je regarde avec des bons yeux, je garderai mon salut, mon \u00e2me, afin de regarder \u00e0 moi-m\u00eame.<\/strong> D\u2019accord?<\/p>\n<p>Je vous embrasse, et demain nous serons ici de retour.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si je regarde avec des bons yeux, je garderai mon salut, mon \u00e2me, afin de regarder \u00e0 moi-m\u00eame.<\/p>\n","protected":false},"author":4,"featured_media":20155,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[27],"tags":[],"class_list":["post-20154","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-jeune-21-jours"],"better_featured_image":{"id":20155,"alt_text":"","caption":"","description":"","media_type":"image","media_details":{"width":1900,"height":757,"file":"2015\/09\/12dia_JD_cor_perverso.jpg","sizes":{"thumbnail":{"file":"12dia_JD_cor_perverso-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/09\/12dia_JD_cor_perverso-150x150.jpg"},"medium":{"file":"12dia_JD_cor_perverso-300x120.jpg","width":300,"height":120,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/09\/12dia_JD_cor_perverso-300x120.jpg"},"large":{"file":"12dia_JD_cor_perverso-1024x408.jpg","width":1024,"height":408,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/09\/12dia_JD_cor_perverso-1024x408.jpg"},"mini-thumbnail":{"file":"12dia_JD_cor_perverso-110x110.jpg","width":110,"height":110,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/09\/12dia_JD_cor_perverso-110x110.jpg"},"big-medium":{"file":"12dia_JD_cor_perverso-320x220.jpg","width":320,"height":220,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/09\/12dia_JD_cor_perverso-320x220.jpg"},"full-post-thumbnail":{"file":"12dia_JD_cor_perverso-1900x748.jpg","width":1900,"height":748,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/09\/12dia_JD_cor_perverso-1900x748.jpg"},"post-thumbnail":{"file":"12dia_JD_cor_perverso-825x325.jpg","width":825,"height":325,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/09\/12dia_JD_cor_perverso-825x325.jpg"}},"image_meta":{"aperture":0,"credit":"","camera":"","caption":"","created_timestamp":0,"copyright":"vali_111 - Fotolia","focal_length":0,"iso":0,"shutter_speed":0,"title":"","orientation":0}},"post":20154,"source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/09\/12dia_JD_cor_perverso.jpg"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>12\u00e8me Jour: \u201cPour Dieu, qu&#039;est-ce un coeur pervers?\u201d - Blog Viviane Freitas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.vivianefreitas.com\/fr\/2015\/10\/01\/12eme-jour-pour-dieu-quest-ce-un-coeur-pervers\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"12\u00e8me Jour: \u201cPour Dieu, qu&#039;est-ce un coeur pervers?\u201d - Blog Viviane Freitas\" \/>\n<meta property=\"og:description\" content=\"Si je regarde avec des bons yeux, je garderai mon salut, mon \u00e2me, afin de regarder \u00e0 moi-m\u00eame.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vivianefreitas.com\/fr\/2015\/10\/01\/12eme-jour-pour-dieu-quest-ce-un-coeur-pervers\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Viviane Freitas\" \/>\n<meta property=\"article:published_time\" content=\"2015-10-01T00:00:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-10-01T09:18:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vivianefreitas.com\/fr\/files\/2015\/09\/12dia_JD_cor_perverso.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1900\" \/>\n\t<meta property=\"og:image:height\" content=\"757\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Viviane Freitas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Viviane Freitas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.vivianefreitas.com\/fr\/2015\/10\/01\/12eme-jour-pour-dieu-quest-ce-un-coeur-pervers\/\",\"url\":\"https:\/\/www.vivianefreitas.com\/fr\/2015\/10\/01\/12eme-jour-pour-dieu-quest-ce-un-coeur-pervers\/\",\"name\":\"12\u00e8me Jour: \u201cPour Dieu, qu'est-ce un coeur pervers?\u201d - Blog Viviane Freitas\",\"isPartOf\":{\"@id\":\"https:\/\/www.vivianefreitas.com\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.vivianefreitas.com\/fr\/2015\/10\/01\/12eme-jour-pour-dieu-quest-ce-un-coeur-pervers\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.vivianefreitas.com\/fr\/2015\/10\/01\/12eme-jour-pour-dieu-quest-ce-un-coeur-pervers\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/09\/12dia_JD_cor_perverso.jpg\",\"datePublished\":\"2015-10-01T00:00:37+00:00\",\"dateModified\":\"2015-10-01T09:18:15+00:00\",\"author\":{\"@id\":\"https:\/\/www.vivianefreitas.com\/fr\/#\/schema\/person\/da4a30407b47e202130ab7d6faa79cd0\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.vivianefreitas.com\/fr\/2015\/10\/01\/12eme-jour-pour-dieu-quest-ce-un-coeur-pervers\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.vivianefreitas.com\/fr\/2015\/10\/01\/12eme-jour-pour-dieu-quest-ce-un-coeur-pervers\/#primaryimage\",\"url\":\"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/09\/12dia_JD_cor_perverso.jpg\",\"contentUrl\":\"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/09\/12dia_JD_cor_perverso.jpg\",\"width\":1900,\"height\":757},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.vivianefreitas.com\/fr\/#website\",\"url\":\"https:\/\/www.vivianefreitas.com\/fr\/\",\"name\":\"Blog Viviane Freitas\",\"description\":\"Bienvenue dans mon Blog\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.vivianefreitas.com\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.vivianefreitas.com\/fr\/#\/schema\/person\/da4a30407b47e202130ab7d6faa79cd0\",\"name\":\"Viviane Freitas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.vivianefreitas.com\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/718ec4eec1bf41a80d57ad6b6a8be8ab?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/718ec4eec1bf41a80d57ad6b6a8be8ab?s=96&d=mm&r=g\",\"caption\":\"Viviane Freitas\"},\"url\":\"https:\/\/www.vivianefreitas.com\/fr\/author\/viviane-freitas\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"12\u00e8me Jour: \u201cPour Dieu, qu'est-ce un coeur pervers?\u201d - Blog Viviane Freitas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.vivianefreitas.com\/fr\/2015\/10\/01\/12eme-jour-pour-dieu-quest-ce-un-coeur-pervers\/","og_locale":"fr_FR","og_type":"article","og_title":"12\u00e8me Jour: \u201cPour Dieu, qu'est-ce un coeur pervers?\u201d - Blog Viviane Freitas","og_description":"Si je regarde avec des bons yeux, je garderai mon salut, mon \u00e2me, afin de regarder \u00e0 moi-m\u00eame.","og_url":"https:\/\/www.vivianefreitas.com\/fr\/2015\/10\/01\/12eme-jour-pour-dieu-quest-ce-un-coeur-pervers\/","og_site_name":"Blog Viviane Freitas","article_published_time":"2015-10-01T00:00:37+00:00","article_modified_time":"2015-10-01T09:18:15+00:00","og_image":[{"width":1900,"height":757,"url":"https:\/\/www.vivianefreitas.com\/fr\/files\/2015\/09\/12dia_JD_cor_perverso.jpg","type":"image\/jpeg"}],"author":"Viviane Freitas","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Viviane Freitas","Dur\u00e9e de lecture estim\u00e9e":"10 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.vivianefreitas.com\/fr\/2015\/10\/01\/12eme-jour-pour-dieu-quest-ce-un-coeur-pervers\/","url":"https:\/\/www.vivianefreitas.com\/fr\/2015\/10\/01\/12eme-jour-pour-dieu-quest-ce-un-coeur-pervers\/","name":"12\u00e8me Jour: \u201cPour Dieu, qu'est-ce un coeur pervers?\u201d - Blog Viviane Freitas","isPartOf":{"@id":"https:\/\/www.vivianefreitas.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vivianefreitas.com\/fr\/2015\/10\/01\/12eme-jour-pour-dieu-quest-ce-un-coeur-pervers\/#primaryimage"},"image":{"@id":"https:\/\/www.vivianefreitas.com\/fr\/2015\/10\/01\/12eme-jour-pour-dieu-quest-ce-un-coeur-pervers\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/09\/12dia_JD_cor_perverso.jpg","datePublished":"2015-10-01T00:00:37+00:00","dateModified":"2015-10-01T09:18:15+00:00","author":{"@id":"https:\/\/www.vivianefreitas.com\/fr\/#\/schema\/person\/da4a30407b47e202130ab7d6faa79cd0"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vivianefreitas.com\/fr\/2015\/10\/01\/12eme-jour-pour-dieu-quest-ce-un-coeur-pervers\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vivianefreitas.com\/fr\/2015\/10\/01\/12eme-jour-pour-dieu-quest-ce-un-coeur-pervers\/#primaryimage","url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/09\/12dia_JD_cor_perverso.jpg","contentUrl":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/09\/12dia_JD_cor_perverso.jpg","width":1900,"height":757},{"@type":"WebSite","@id":"https:\/\/www.vivianefreitas.com\/fr\/#website","url":"https:\/\/www.vivianefreitas.com\/fr\/","name":"Blog Viviane Freitas","description":"Bienvenue dans mon Blog","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vivianefreitas.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.vivianefreitas.com\/fr\/#\/schema\/person\/da4a30407b47e202130ab7d6faa79cd0","name":"Viviane Freitas","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vivianefreitas.com\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/718ec4eec1bf41a80d57ad6b6a8be8ab?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/718ec4eec1bf41a80d57ad6b6a8be8ab?s=96&d=mm&r=g","caption":"Viviane Freitas"},"url":"https:\/\/www.vivianefreitas.com\/fr\/author\/viviane-freitas\/"}]}},"jetpack_featured_media_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/09\/12dia_JD_cor_perverso.jpg","_links":{"self":[{"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/posts\/20154","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/comments?post=20154"}],"version-history":[{"count":3,"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/posts\/20154\/revisions"}],"predecessor-version":[{"id":20158,"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/posts\/20154\/revisions\/20158"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/media\/20155"}],"wp:attachment":[{"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/media?parent=20154"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/categories?post=20154"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/tags?post=20154"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}