{"id":20136,"date":"2015-09-29T09:15:44","date_gmt":"2015-09-29T09:15:44","guid":{"rendered":"http:\/\/www.vivianefreitas.com\/fr\/?p=20136"},"modified":"2015-09-29T09:15:44","modified_gmt":"2015-09-29T09:15:44","slug":"fausse-sensation-de-bien-etre","status":"publish","type":"post","link":"https:\/\/www.vivianefreitas.com\/fr\/2015\/09\/29\/fausse-sensation-de-bien-etre\/","title":{"rendered":"Fausse sensation de bien-\u00eatre!"},"content":{"rendered":"<p style=\"text-align: center;\"><strong>Ceci est un probl\u00e8me tr\u00e8s grave!<\/strong><\/p>\n<p>Lorsqu&rsquo;une personne souffre beaucoup dans son int\u00e9rieur, elle vit des angoisses, peurs, ins\u00e9curit\u00e9s, vous cherchez un refuge, et si on parlait de la \u201cfoi sentimentale\u201d, le refuge est \u00ab\u00a0de faire pour Dieu\u00a0\u00bb et vous commencez \u00e0 vous occuper, mais cela ne r\u00e9sout pas le probl\u00e8me qui est \u00ab\u00a0\u00e0 l&rsquo;int\u00e9rieur\u00a0\u00bb. Et au fil du temps, vous commencez \u00e0 vous justifier par ce que vous faites, \u00ab\u00a0Oh &#8230; je prie, je participe des \u00e9v\u00e9nements pour les jeunes, je vais \u00e0 l&rsquo;\u00e9glise, j&rsquo;ai invit\u00e9 une personne \u00e0 participer de la r\u00e9union, je suis fid\u00e8le \u00e0 la d\u00eeme, j&rsquo;aide les personnes. etc. \u00a0\u00bb<\/p>\n<p style=\"text-align: center;\"><em><strong>Mais cette douleur, ce probl\u00e8me, insiste \u00e0 rester \u00e0 l&rsquo;int\u00e9rieur. Et le temps passe, et pour agir d&rsquo;une mani\u00e8re religieuse, vous commencez \u00e0 vous tromper par cette <span style=\"text-decoration: underline;\">fausse sensation de bien-\u00eatre<\/span>, pour ce que vous faites et non pas par qui vous \u00eates et ce que vous croyez!<\/strong><\/em><\/p>\n<p>Ch\u00e9rie, on ne peut donner que ce que nous avons, et si vous vous cachez derri\u00e8re les coutumes religieuses, vous serez frustr\u00e9e, mais si vous vous concentrez sur votre \u00e2me et si vous ne perdez jamais la vision que vous avez besoin de salut, vous serez toujours \u00e0 la recherche pour r\u00e9soudre leurs conflits int\u00e9rieurs avec Dieu, et ne pas les cach\u00e9s de Dieu!<\/p>\n<p>Observez les paroles du Seigneur J\u00e9sus:<\/p>\n<blockquote><p>\u00ab\u00a0M\u00eame si vous aussi vers l&rsquo;ext\u00e9rieur justes aux hommes, il semble, mais \u00e0 l&rsquo;int\u00e9rieur vous \u00eates pleins d&rsquo;hypocrisie et d&rsquo;iniquit\u00e9.\u00a0\u00bb<br \/>\n(Matthieu 23:28)<\/p><\/blockquote>\n<p><span style=\"text-decoration: underline;\">Le Seigneur J\u00e9sus parle aux pharisiens qui suivaient les lois, mais leur c\u0153ur \u00e9tait loin de Lui!<\/span><\/p>\n<p>Cela est inutile d&rsquo;essayer de prouver aux gens que vous \u00eates de Dieu, car Dieu sait et voit tout! Soyez sinc\u00e8re, exposer votre \u00e9tat r\u00e9el et demandez de l&rsquo;aide!<\/p>\n<blockquote><p>\u00ab\u00a0Approchez-vous de Dieu et il approchera de vous Nettoyez vos mains, p\u00e9cheurs ; Et, hommes irr\u00e9solus, purifiez vos coeurs.\u00a0\u00bb (Jacques 4: 8)<\/p><\/blockquote>\n<p>Dieu nous donne l&rsquo;opportunit\u00e9 de recommencer! Donc profitez de l&rsquo;occasion et commencez d\u00e8s maintenant \u00e0 vous rapprocher de Lui, et quand Il s&rsquo;approchera de vous, vous aurez de la paix, certitude, force, courage, et tout sera vrai en vous et dans votre vie!<\/p>\n<p>Que Dieu vous b\u00e9nisse et \u00e0 la semaine prochaine!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cela est inutile d&rsquo;essayer de prouver aux gens que vous \u00eates de Dieu, car Dieu sait et voit tout!<\/p>\n","protected":false},"author":516,"featured_media":20137,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-20136","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-jeunes"],"better_featured_image":{"id":20137,"alt_text":"","caption":"","description":"","media_type":"image","media_details":{"width":1900,"height":710,"file":"2015\/09\/falsa_sensacao_jovens.jpg","sizes":{"thumbnail":{"file":"falsa_sensacao_jovens-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/09\/falsa_sensacao_jovens-150x150.jpg"},"medium":{"file":"falsa_sensacao_jovens-300x112.jpg","width":300,"height":112,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/09\/falsa_sensacao_jovens-300x112.jpg"},"large":{"file":"falsa_sensacao_jovens-1024x383.jpg","width":1024,"height":383,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/09\/falsa_sensacao_jovens-1024x383.jpg"},"mini-thumbnail":{"file":"falsa_sensacao_jovens-110x110.jpg","width":110,"height":110,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/09\/falsa_sensacao_jovens-110x110.jpg"},"big-medium":{"file":"falsa_sensacao_jovens-320x220.jpg","width":320,"height":220,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/09\/falsa_sensacao_jovens-320x220.jpg"},"full-post-thumbnail":{"file":"falsa_sensacao_jovens-1900x748.jpg","width":1900,"height":748,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/09\/falsa_sensacao_jovens-1900x748.jpg"},"post-thumbnail":{"file":"falsa_sensacao_jovens-825x325.jpg","width":825,"height":325,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/09\/falsa_sensacao_jovens-825x325.jpg"}},"image_meta":{"aperture":0,"credit":"","camera":"","caption":"","created_timestamp":0,"copyright":"ave_mario - Fotolia","focal_length":0,"iso":0,"shutter_speed":0,"title":"","orientation":0}},"post":20136,"source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/09\/falsa_sensacao_jovens.jpg"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fausse sensation de bien-\u00eatre! - Blog Viviane Freitas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.vivianefreitas.com\/fr\/2015\/09\/29\/fausse-sensation-de-bien-etre\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fausse sensation de bien-\u00eatre! - Blog Viviane Freitas\" \/>\n<meta property=\"og:description\" content=\"Cela est inutile d&#039;essayer de prouver aux gens que vous \u00eates de Dieu, car Dieu sait et voit tout!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vivianefreitas.com\/fr\/2015\/09\/29\/fausse-sensation-de-bien-etre\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Viviane Freitas\" \/>\n<meta property=\"article:published_time\" content=\"2015-09-29T09:15:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vivianefreitas.com\/fr\/files\/2015\/09\/falsa_sensacao_jovens.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1900\" \/>\n\t<meta property=\"og:image:height\" content=\"710\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Elaine Rocha\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Elaine Rocha\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.vivianefreitas.com\/fr\/2015\/09\/29\/fausse-sensation-de-bien-etre\/\",\"url\":\"https:\/\/www.vivianefreitas.com\/fr\/2015\/09\/29\/fausse-sensation-de-bien-etre\/\",\"name\":\"Fausse sensation de bien-\u00eatre! - Blog Viviane Freitas\",\"isPartOf\":{\"@id\":\"https:\/\/www.vivianefreitas.com\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.vivianefreitas.com\/fr\/2015\/09\/29\/fausse-sensation-de-bien-etre\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.vivianefreitas.com\/fr\/2015\/09\/29\/fausse-sensation-de-bien-etre\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/09\/falsa_sensacao_jovens.jpg\",\"datePublished\":\"2015-09-29T09:15:44+00:00\",\"author\":{\"@id\":\"https:\/\/www.vivianefreitas.com\/fr\/#\/schema\/person\/7cfc6310cff444d28c2cd0e61aac6ade\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.vivianefreitas.com\/fr\/2015\/09\/29\/fausse-sensation-de-bien-etre\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.vivianefreitas.com\/fr\/2015\/09\/29\/fausse-sensation-de-bien-etre\/#primaryimage\",\"url\":\"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/09\/falsa_sensacao_jovens.jpg\",\"contentUrl\":\"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/09\/falsa_sensacao_jovens.jpg\",\"width\":1900,\"height\":710},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.vivianefreitas.com\/fr\/#website\",\"url\":\"https:\/\/www.vivianefreitas.com\/fr\/\",\"name\":\"Blog Viviane Freitas\",\"description\":\"Bienvenue dans mon Blog\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.vivianefreitas.com\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.vivianefreitas.com\/fr\/#\/schema\/person\/7cfc6310cff444d28c2cd0e61aac6ade\",\"name\":\"Elaine Rocha\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.vivianefreitas.com\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a48b6a068cf6b8848123d4ca65a1d037?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a48b6a068cf6b8848123d4ca65a1d037?s=96&d=mm&r=g\",\"caption\":\"Elaine Rocha\"},\"url\":\"https:\/\/www.vivianefreitas.com\/fr\/author\/elaarocha\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fausse sensation de bien-\u00eatre! - Blog Viviane Freitas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.vivianefreitas.com\/fr\/2015\/09\/29\/fausse-sensation-de-bien-etre\/","og_locale":"fr_FR","og_type":"article","og_title":"Fausse sensation de bien-\u00eatre! - Blog Viviane Freitas","og_description":"Cela est inutile d'essayer de prouver aux gens que vous \u00eates de Dieu, car Dieu sait et voit tout!","og_url":"https:\/\/www.vivianefreitas.com\/fr\/2015\/09\/29\/fausse-sensation-de-bien-etre\/","og_site_name":"Blog Viviane Freitas","article_published_time":"2015-09-29T09:15:44+00:00","og_image":[{"width":1900,"height":710,"url":"https:\/\/www.vivianefreitas.com\/fr\/files\/2015\/09\/falsa_sensacao_jovens.jpg","type":"image\/jpeg"}],"author":"Elaine Rocha","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Elaine Rocha","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.vivianefreitas.com\/fr\/2015\/09\/29\/fausse-sensation-de-bien-etre\/","url":"https:\/\/www.vivianefreitas.com\/fr\/2015\/09\/29\/fausse-sensation-de-bien-etre\/","name":"Fausse sensation de bien-\u00eatre! - Blog Viviane Freitas","isPartOf":{"@id":"https:\/\/www.vivianefreitas.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vivianefreitas.com\/fr\/2015\/09\/29\/fausse-sensation-de-bien-etre\/#primaryimage"},"image":{"@id":"https:\/\/www.vivianefreitas.com\/fr\/2015\/09\/29\/fausse-sensation-de-bien-etre\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/09\/falsa_sensacao_jovens.jpg","datePublished":"2015-09-29T09:15:44+00:00","author":{"@id":"https:\/\/www.vivianefreitas.com\/fr\/#\/schema\/person\/7cfc6310cff444d28c2cd0e61aac6ade"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vivianefreitas.com\/fr\/2015\/09\/29\/fausse-sensation-de-bien-etre\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vivianefreitas.com\/fr\/2015\/09\/29\/fausse-sensation-de-bien-etre\/#primaryimage","url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/09\/falsa_sensacao_jovens.jpg","contentUrl":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/09\/falsa_sensacao_jovens.jpg","width":1900,"height":710},{"@type":"WebSite","@id":"https:\/\/www.vivianefreitas.com\/fr\/#website","url":"https:\/\/www.vivianefreitas.com\/fr\/","name":"Blog Viviane Freitas","description":"Bienvenue dans mon Blog","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vivianefreitas.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.vivianefreitas.com\/fr\/#\/schema\/person\/7cfc6310cff444d28c2cd0e61aac6ade","name":"Elaine Rocha","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vivianefreitas.com\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a48b6a068cf6b8848123d4ca65a1d037?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a48b6a068cf6b8848123d4ca65a1d037?s=96&d=mm&r=g","caption":"Elaine Rocha"},"url":"https:\/\/www.vivianefreitas.com\/fr\/author\/elaarocha\/"}]}},"jetpack_featured_media_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/09\/falsa_sensacao_jovens.jpg","_links":{"self":[{"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/posts\/20136","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/users\/516"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/comments?post=20136"}],"version-history":[{"count":1,"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/posts\/20136\/revisions"}],"predecessor-version":[{"id":20138,"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/posts\/20136\/revisions\/20138"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/media\/20137"}],"wp:attachment":[{"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/media?parent=20136"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/categories?post=20136"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/tags?post=20136"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}