{"id":20033,"date":"2015-09-05T09:00:00","date_gmt":"2015-09-05T09:00:00","guid":{"rendered":"http:\/\/www.vivianefreitas.com\/fr\/?p=20033"},"modified":"2015-09-07T17:40:28","modified_gmt":"2015-09-07T17:40:28","slug":"il-ne-ressent-aucun-plaisir-dans-les-choses-de-dieu","status":"publish","type":"post","link":"https:\/\/www.vivianefreitas.com\/fr\/2015\/09\/05\/il-ne-ressent-aucun-plaisir-dans-les-choses-de-dieu\/","title":{"rendered":"\u00ab\u00a0Il ne ressent aucun plaisir dans les choses de Dieu&#8230;\u00a0\u00bb"},"content":{"rendered":"<p><em><strong>Bonjour, Madame Viviane.<\/strong><\/em><\/p>\n<p>Je m\u2019appelle Eloisa Ester, je suis \u00e9pouse du pasteur, ici en Colombie, et je suis en train de suivre ce que vous avez pass\u00e9 avec l\u2019\u00e9v\u00eaque Julio, au sujet de vos enfants, et la fa\u00e7on dont Dieu vous a donn\u00e9 la victoire. <em><strong>J\u2019ai un fils de 16 ans, nous avons adopt\u00e9 quand il avait trois jours de vie, aujourd\u2019hui, il nous a rendu triste plusieurs fois avec ses attitudes; il ne ressent aucun plaisir dans les choses de Dieu<\/strong><\/em>, comme nous l&rsquo;avons enseign\u00e9, mais maintenant qu\u2019il a grandi, il a beaucoup chang\u00e9 &#8230; Il veut \u00eatre un joueur de football.<\/p>\n<p>Nous ne le condamnons pas, mais nous le soutenons, nous lui montrons, qu&rsquo;il a besoin en premier lieu, besoin du Seigneur J\u00e9sus et de son salut, mais je vous l\u2019avoue, que parfois il me manque patience. Je cherche \u00e0 l\u2019orienter au sujet des amiti\u00e9s, mais il fait tout \u00e0 l&rsquo;envers. Mon mari, l\u2019oriente beaucoup, et parfois pas il ne l\u2019accepte pas. Il a d\u00e9j\u00e0 perc\u00e9 une oreille afin de porter des boucles d&rsquo;oreilles et maintenant, il veut tatou\u00e9 sur le bras un mot, nous avons dit non, que cela n\u2019est pas de Dieu, mais il dit que c\u2019est juste un mot &#8230;<\/p>\n<p style=\"text-align: left;\">Madame Viviane, je vais la chaine de pri\u00e8re du vendredi en faveur de sa d\u00e9livrance, je participe de tous les propos, en particulier celui de la famille, et nous avons fait notre sacrifice dans la derni\u00e8re Campagne d\u2019Isra\u00ebl et je crois que Dieu va le transformer, je ne doute pas! J&rsquo;ai particip\u00e9 de la pri\u00e8re que vous avez fait avec l\u2019\u00e9v\u00eaque Julio et vos enfants, en faveur de la famille, et j\u2019ai eu donc envie de vous \u00e9crire, afin que vous et votre famille si belle puissent nous aider en pri\u00e8re et orientation.<\/p>\n<p>Il s\u2019appelle Matheus Madeira Martins. Dieu b\u00e9nisse, \u00e0 vous et \u00e0 votre famille.<\/p>\n<p style=\"text-align: right;\">&#8211;\u00a0<a href=\"https:\/\/www.facebook.com\/eloisaester.madeiramartins\" target=\"_blank\" name=\"ecxjs_41\"><span style=\"color: #000000;\"><span style=\"font-family: Avenir;\"><span lang=\"fr-FR\"><b>Eloisa Ester Madeira Martins<\/b><\/span><\/span><\/span><\/a><\/p>\n<blockquote><p><strong>Ch\u00e8re Eloise<\/strong><em>,<\/em><\/p>\n<p><em><span style=\"text-decoration: underline;\"><strong>Les enfants de pasteurs et d\u2019\u00e9v\u00eaques ont une excellente opportunit\u00e9 de chercher \u00e0 Dieu<\/strong><\/span>, car s\u00fbrement leurs parents ont pr\u00e9sent\u00e9 Dieu \u00e0 la maison, mais par envie de vouloir conna\u00eetre le monde ou de vivre en \u00ablibert\u00e9\u00bb, ils pensent qu&rsquo;ils sont \u00abprisonniers\u00bb \u00e0 quelque chose.<\/em><\/p>\n<p><em>Vous, en tant que m\u00e8re, vous devez faire votre part: enseigner, \u00e9couter. Aller dans son monde, dans l\u2019objectif de lui faire comprendre. Mais votre premi\u00e8re pr\u00e9occupation, ne doit pas \u00eatre votre enfant. Elle doit \u00eatre de servir \u00e0 Dieu. Le r\u00f4le du p\u00e8re est tr\u00e8s important. C&rsquo;est lui qui poses les r\u00e8gles \u00e0 la maison.<\/em><\/p>\n<p><em>Je vais parler de ce que j\u2019ai vu dans Julio, au moment o\u00f9 Louis et Vera sont arriv\u00e9s \u2026 Julio a impos\u00e9 comment cela serait \u00e0 la maison: s&rsquo;ils ne voulaient pas suivre la voix de servir \u00e0 Dieu, la m\u00eame porte qui \u00e9tait ouverte afin de les aider, \u00e9tait aussi ouverte pour qu\u2019ils sortent. \u00c9tant donn\u00e9, que nous vivons dans la maison qui appartient \u00e0 l&rsquo;\u00c9glise, qui est soutenu par des offrandes et des sacrifices. Donc, ceux qui doivent y vivre, sont ceux qui sacrifient aussi.<\/em><\/p>\n<p style=\"text-align: center;\"><strong><em>Si votre fils est majeur, il peut d\u00e9j\u00e0 travailler.<\/em><\/strong><\/p>\n<p><em>S\u2019il veut suivre son chemin avec des mauvais choix, alors qu\u2019il cherche un emploi et qu\u2019il vive de son travail. Et non du sacrifice d&rsquo;autrui ou du v\u00f4tre.<\/em><\/p>\n<p><em>Voil\u00e0, comment je vois au sujet de l&rsquo;\u0153uvre de Dieu.<\/em><\/p>\n<p><em>Louis et Vera, ils sont conscients qu\u2019\u00e0 la maison nous avons des r\u00e8gles, du respect envers ce qui est de l&rsquo;autel.<\/em><\/p>\n<p><em>Nous vivons de l&rsquo;autel, et \u00e0 cause de l\u2019Autel, nous sacrifions toutes nos vies. Il n\u2019est pas juste de sacrifier notre vie, et avoir un \u00eatre qui ne veut pas chercher Dieu et nous distrait pour ce que nous avons \u00e9t\u00e9 appel\u00e9s.<\/em><\/p>\n<p><em>Tant que votre fils \u00e9tait petit et n\u2019avait aucune notion, vous avez donn\u00e9, vous avez pris soin, vous avez renonc\u00e9. Maintenant, vous n\u2019avez pas \u00e0 vivre avec ses erreurs. S\u2019il ne veut pas accepter les r\u00e8gles que vous lui donnez, il ne devrait pas \u00eatre le bienvenu chez vous.<\/em><\/p>\n<p><em>Avec quel argent, il a perc\u00e9 l\u2019oreille et a mis la boucle d&rsquo;oreille?<\/em><\/p>\n<p><em>Mon \u00e9poux esp\u00e8re qui cela n&rsquo;a pas \u00e9t\u00e9 avec votre argent. Car si c\u2019est ainsi, vous \u00eates en partie coupable de votre erreur.<\/em><\/p>\n<p style=\"text-align: center;\"><strong><em>La foi est la ferme assurance des choses que l&rsquo;on esp\u00e8re et la conviction des choses que l&rsquo;on ne voit pas.<\/em><\/strong><\/p>\n<p><em>Si vous servez \u00e0 Dieu et vous avez la conviction de ce qui est l&rsquo;autel, lieu du sacrifice, vous voyez d&rsquo;abord ceci. Vous respectez et vous avez du z\u00e8le d&rsquo;\u00eatre et de faire quelque chose de pr\u00e9sentable \u00e0 Dieu.<\/em><\/p>\n<p><em>Mais s\u2019il y a le doute, il y a la peur &#8230; et vous ne prenez pas le contr\u00f4le de la situation&#8230;<\/em><\/p>\n<p><em>Julio a mentionn\u00e9 lors de la r\u00e9union de mercredi, ici au Templo Maior, que les deux espions (Josu\u00e9 et Caleb), lorsqu\u2019ils sont all\u00e9s vers la terre, ils ont vu une opportunit\u00e9, m\u00eame devant les adversit\u00e9s. Et il a dit quelque chose qui a vraiment attir\u00e9 mon attention: que les fid\u00e8les sont courageux!<\/em><\/p>\n<p><em>Qui est fid\u00e8le? <\/em><span style=\"text-decoration: underline;\"><strong>Le courageux pour ob\u00e9ir.<\/strong><\/span><\/p>\n<p><em>Et le simple fait de donner la priorit\u00e9 \u00e0 Dieu et de le laisser prendre soin de lui, sans sentiments de piti\u00e9, vous serez courageuse et par cons\u00e9quent, fid\u00e8le \u00e0 Dieu.<\/em><\/p><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>J&rsquo;ai un fils de 16 ans; il nous a rendu triste plusieurs fois avec ses attitudes.<\/p>\n","protected":false},"author":4,"featured_media":20034,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[43],"tags":[],"class_list":["post-20033","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-reponse-aux-internautes"],"better_featured_image":{"id":20034,"alt_text":"","caption":"","description":"","media_type":"image","media_details":{"width":1900,"height":753,"file":"2015\/09\/rep_filho_rebelde.jpg","sizes":{"thumbnail":{"file":"rep_filho_rebelde-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/09\/rep_filho_rebelde-150x150.jpg"},"medium":{"file":"rep_filho_rebelde-300x119.jpg","width":300,"height":119,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/09\/rep_filho_rebelde-300x119.jpg"},"large":{"file":"rep_filho_rebelde-1024x406.jpg","width":1024,"height":406,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/09\/rep_filho_rebelde-1024x406.jpg"},"mini-thumbnail":{"file":"rep_filho_rebelde-110x110.jpg","width":110,"height":110,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/09\/rep_filho_rebelde-110x110.jpg"},"big-medium":{"file":"rep_filho_rebelde-320x220.jpg","width":320,"height":220,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/09\/rep_filho_rebelde-320x220.jpg"},"full-post-thumbnail":{"file":"rep_filho_rebelde-1900x748.jpg","width":1900,"height":748,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/09\/rep_filho_rebelde-1900x748.jpg"},"post-thumbnail":{"file":"rep_filho_rebelde-825x325.jpg","width":825,"height":325,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/09\/rep_filho_rebelde-825x325.jpg"}},"image_meta":{"aperture":0,"credit":"","camera":"","caption":"","created_timestamp":0,"copyright":"BlueSkyImages - Fotolia","focal_length":0,"iso":0,"shutter_speed":0,"title":"","orientation":0}},"post":20033,"source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/09\/rep_filho_rebelde.jpg"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>&quot;Il ne ressent aucun plaisir dans les choses de Dieu...&quot; - Blog Viviane Freitas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.vivianefreitas.com\/fr\/2015\/09\/05\/il-ne-ressent-aucun-plaisir-dans-les-choses-de-dieu\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Il ne ressent aucun plaisir dans les choses de Dieu...&quot; - Blog Viviane Freitas\" \/>\n<meta property=\"og:description\" content=\"J&#039;ai un fils de 16 ans; il nous a rendu triste plusieurs fois avec ses attitudes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vivianefreitas.com\/fr\/2015\/09\/05\/il-ne-ressent-aucun-plaisir-dans-les-choses-de-dieu\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Viviane Freitas\" \/>\n<meta property=\"article:published_time\" content=\"2015-09-05T09:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-09-07T17:40:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vivianefreitas.com\/fr\/files\/2015\/09\/rep_filho_rebelde.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1900\" \/>\n\t<meta property=\"og:image:height\" content=\"753\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Viviane Freitas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Viviane Freitas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.vivianefreitas.com\/fr\/2015\/09\/05\/il-ne-ressent-aucun-plaisir-dans-les-choses-de-dieu\/\",\"url\":\"https:\/\/www.vivianefreitas.com\/fr\/2015\/09\/05\/il-ne-ressent-aucun-plaisir-dans-les-choses-de-dieu\/\",\"name\":\"\\\"Il ne ressent aucun plaisir dans les choses de Dieu...\\\" - Blog Viviane Freitas\",\"isPartOf\":{\"@id\":\"https:\/\/www.vivianefreitas.com\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.vivianefreitas.com\/fr\/2015\/09\/05\/il-ne-ressent-aucun-plaisir-dans-les-choses-de-dieu\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.vivianefreitas.com\/fr\/2015\/09\/05\/il-ne-ressent-aucun-plaisir-dans-les-choses-de-dieu\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/09\/rep_filho_rebelde.jpg\",\"datePublished\":\"2015-09-05T09:00:00+00:00\",\"dateModified\":\"2015-09-07T17:40:28+00:00\",\"author\":{\"@id\":\"https:\/\/www.vivianefreitas.com\/fr\/#\/schema\/person\/da4a30407b47e202130ab7d6faa79cd0\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.vivianefreitas.com\/fr\/2015\/09\/05\/il-ne-ressent-aucun-plaisir-dans-les-choses-de-dieu\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.vivianefreitas.com\/fr\/2015\/09\/05\/il-ne-ressent-aucun-plaisir-dans-les-choses-de-dieu\/#primaryimage\",\"url\":\"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/09\/rep_filho_rebelde.jpg\",\"contentUrl\":\"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/09\/rep_filho_rebelde.jpg\",\"width\":1900,\"height\":753},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.vivianefreitas.com\/fr\/#website\",\"url\":\"https:\/\/www.vivianefreitas.com\/fr\/\",\"name\":\"Blog Viviane Freitas\",\"description\":\"Bienvenue dans mon Blog\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.vivianefreitas.com\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.vivianefreitas.com\/fr\/#\/schema\/person\/da4a30407b47e202130ab7d6faa79cd0\",\"name\":\"Viviane Freitas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.vivianefreitas.com\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/718ec4eec1bf41a80d57ad6b6a8be8ab?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/718ec4eec1bf41a80d57ad6b6a8be8ab?s=96&d=mm&r=g\",\"caption\":\"Viviane Freitas\"},\"url\":\"https:\/\/www.vivianefreitas.com\/fr\/author\/viviane-freitas\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"Il ne ressent aucun plaisir dans les choses de Dieu...\" - Blog Viviane Freitas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.vivianefreitas.com\/fr\/2015\/09\/05\/il-ne-ressent-aucun-plaisir-dans-les-choses-de-dieu\/","og_locale":"fr_FR","og_type":"article","og_title":"\"Il ne ressent aucun plaisir dans les choses de Dieu...\" - Blog Viviane Freitas","og_description":"J'ai un fils de 16 ans; il nous a rendu triste plusieurs fois avec ses attitudes.","og_url":"https:\/\/www.vivianefreitas.com\/fr\/2015\/09\/05\/il-ne-ressent-aucun-plaisir-dans-les-choses-de-dieu\/","og_site_name":"Blog Viviane Freitas","article_published_time":"2015-09-05T09:00:00+00:00","article_modified_time":"2015-09-07T17:40:28+00:00","og_image":[{"width":1900,"height":753,"url":"https:\/\/www.vivianefreitas.com\/fr\/files\/2015\/09\/rep_filho_rebelde.jpg","type":"image\/jpeg"}],"author":"Viviane Freitas","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Viviane Freitas","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.vivianefreitas.com\/fr\/2015\/09\/05\/il-ne-ressent-aucun-plaisir-dans-les-choses-de-dieu\/","url":"https:\/\/www.vivianefreitas.com\/fr\/2015\/09\/05\/il-ne-ressent-aucun-plaisir-dans-les-choses-de-dieu\/","name":"\"Il ne ressent aucun plaisir dans les choses de Dieu...\" - Blog Viviane Freitas","isPartOf":{"@id":"https:\/\/www.vivianefreitas.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vivianefreitas.com\/fr\/2015\/09\/05\/il-ne-ressent-aucun-plaisir-dans-les-choses-de-dieu\/#primaryimage"},"image":{"@id":"https:\/\/www.vivianefreitas.com\/fr\/2015\/09\/05\/il-ne-ressent-aucun-plaisir-dans-les-choses-de-dieu\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/09\/rep_filho_rebelde.jpg","datePublished":"2015-09-05T09:00:00+00:00","dateModified":"2015-09-07T17:40:28+00:00","author":{"@id":"https:\/\/www.vivianefreitas.com\/fr\/#\/schema\/person\/da4a30407b47e202130ab7d6faa79cd0"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vivianefreitas.com\/fr\/2015\/09\/05\/il-ne-ressent-aucun-plaisir-dans-les-choses-de-dieu\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vivianefreitas.com\/fr\/2015\/09\/05\/il-ne-ressent-aucun-plaisir-dans-les-choses-de-dieu\/#primaryimage","url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/09\/rep_filho_rebelde.jpg","contentUrl":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/09\/rep_filho_rebelde.jpg","width":1900,"height":753},{"@type":"WebSite","@id":"https:\/\/www.vivianefreitas.com\/fr\/#website","url":"https:\/\/www.vivianefreitas.com\/fr\/","name":"Blog Viviane Freitas","description":"Bienvenue dans mon Blog","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vivianefreitas.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.vivianefreitas.com\/fr\/#\/schema\/person\/da4a30407b47e202130ab7d6faa79cd0","name":"Viviane Freitas","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vivianefreitas.com\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/718ec4eec1bf41a80d57ad6b6a8be8ab?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/718ec4eec1bf41a80d57ad6b6a8be8ab?s=96&d=mm&r=g","caption":"Viviane Freitas"},"url":"https:\/\/www.vivianefreitas.com\/fr\/author\/viviane-freitas\/"}]}},"jetpack_featured_media_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/09\/rep_filho_rebelde.jpg","_links":{"self":[{"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/posts\/20033","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/comments?post=20033"}],"version-history":[{"count":1,"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/posts\/20033\/revisions"}],"predecessor-version":[{"id":20035,"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/posts\/20033\/revisions\/20035"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/media\/20034"}],"wp:attachment":[{"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/media?parent=20033"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/categories?post=20033"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/tags?post=20033"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}