{"id":19266,"date":"2015-04-16T09:20:14","date_gmt":"2015-04-16T09:20:14","guid":{"rendered":"http:\/\/www.vivianefreitas.com\/fr\/?p=19266"},"modified":"2015-04-16T09:20:14","modified_gmt":"2015-04-16T09:20:14","slug":"sante-etre-positif-fait-du-bien-a-la-sante","status":"publish","type":"post","link":"https:\/\/www.vivianefreitas.com\/fr\/2015\/04\/16\/sante-etre-positif-fait-du-bien-a-la-sante\/","title":{"rendered":"Sant\u00e9: \u00catre positif fait du bien \u00e0 la sant\u00e9!"},"content":{"rendered":"<p><p class=\"intro\">Comment le fait d&rsquo;\u00eatre positif ou n\u00e9gatif peuvent avoir une influence sur notre sant\u00e9?<\/p><br \/>\n<!--more--><\/p>\n<p>En demininuant ou en augmentant le stress, anxi\u00e9t\u00e9, l&rsquo;insomnie, les nerfs et beaucoup d&rsquo;autres choses que nous allons en parl\u00e9s aujourd&rsquo;hui.<\/p>\n<p>Imaginons que nous entrons dans une course de cents m\u00e8tres, mais on a deux options: une avec des barri\u00e8res et une autre sans barri\u00e8res. On doit faire face \u00e0 cela tous les jours,  m\u00eame en ayant des probl\u00e8mes, nous pouvons regarder notre objectif auquel on se propre, sans barri\u00e8res quand on est positifs ou avec barri\u00e8res en \u00e9tant n\u00e9gatifs!<\/p>\n<p>Mais comment peuvent-ils avoir de l\u2019influence sur votre sant\u00e9?<br \/>\nSi nous voyons beaucoup de barri\u00e8res, on pense toute de suite qu&rsquo;on devra faire un grand effort, on commence \u00e0 penser aux probl\u00e8mes qui arriveront et on commence \u00e0 souffrir \u00e0 l&rsquo;avance et comme r\u00e9sultat surgit l&rsquo;anxi\u00e9t\u00e9, les nerfs, les insomnies, le stress et dans de nombreux cas la d\u00e9pression. \u00c0 son tour, le fait de ne pas bien dormir, on est toujours anxieuses ou angoiss\u00e9es et en ayant peur de tout qui puisse arriver. Cela commence a affecter notre organisme, ce qui peut provoquer des ulc\u00e8res \u00e0 l&rsquo;estomac, des changements dans le fonctionnement des intestins, probl\u00e8mes cardiaques et la liste est longue. <\/p>\n<p>A tout cela, nous devons ajout\u00e9s que nous devenons anti-sociales quand nous devenons des personnes n\u00e9gatives, qui arrive \u00e0 vivre aux c\u00f4t\u00e9s de quelqu&rsquo;un qui voit des obstacles en tout et pour qui tout est compliqu\u00e9? <\/p>\n<p>Au contraire une personne positive est \u00e9quilibr\u00e9e et arrive \u00e0 g\u00e9rer de la meilleur fa\u00e7on l&rsquo;impact que nos probl\u00e8mes quotidiens causent \u00e0 notre bien-\u00eatre. Cette capacit\u00e9 aide \u00e0 prevenir de nombreuses maladies neurologiques et gastrointestinale. <\/p>\n<p>C&rsquo;est clair que les positifs doit faire face aux obstacles, et dans certains cas, surtout les personnes n\u00e9gatives parce qu&rsquo;ils se lancent, produisent, id\u00e9alisent et sont toujours actifs, ils ont une vie bien charg\u00e9e, et d\u00e8s lors se multiplient les probl\u00e8mes. Cependant lorsque l&rsquo;on est positif, le bon sens, la tranquillit\u00e9 et l&rsquo;\u00e9quilibre que vous poss\u00e9dez, vous permet de faire face \u00e0 chaque d\u00e9fi comme une opportunit\u00e9 et non pas une barri\u00e8re infranchissable. Jusqu&rsquo;\u00e0 ce qu&rsquo;elles font face \u00e0 un probl\u00e8me de sant\u00e9 provoqu\u00e9 par une r\u00e9action inattendue du corps, mais qui y font face de fa\u00e7on positive et cela est tr\u00e8s d\u00e9cisive pour le traitement. <\/p>\n<p><em>\u201cMais comment faire?\u201d<\/em>, vous devez vous demander. <\/p>\n<p>Les personnes diront, j&rsquo;ai toujours \u00e9t\u00e9 comme \u00e7a, pessimiste&#8230; Si vous \u00eates comme cela, pensez-y, quel b\u00e9n\u00e9fice cela apporte \u00e0 votre sant\u00e9? Je crois que la r\u00e9ponse doit \u00eatre aucune&#8230; <\/p>\n<p>Alors faites un test!<br \/>\nCommencez \u00e0 croire en vous-m\u00eame&#8230;<br \/>\nChangez votre mani\u00e8re de voir la vie, \u00e9liminez les obstacles que vous avez cr\u00e9\u00e9 et regardez votre objectif, bien certaine que vous y arriverez.<\/p>\n<p>R\u00e9veillez-vous de bonne humeur, programmez votre jour, faites face aux situations que vous avez peur.<br \/>\nVotre sant\u00e9 vous remerciera beaucoup!<\/p>\n<p>A la prochaine et soyez <strong><em>POSITIVES<\/strong><\/em>! <\/p>\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":4,"featured_media":19267,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[13,32],"tags":[],"class_list":["post-19266","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sante","category-sante-barbara-filipe"],"better_featured_image":{"id":19267,"alt_text":"","caption":"","description":"","media_type":"image","media_details":{"width":660,"height":261,"file":"2015\/04\/stress.jpg","sizes":{"thumbnail":{"file":"stress-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/04\/stress-150x150.jpg"},"medium":{"file":"stress-300x118.jpg","width":300,"height":118,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/04\/stress-300x118.jpg"},"blogintro":{"file":"stress-144x100.jpg","width":144,"height":100,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/04\/stress-144x100.jpg"},"onethirdsquare":{"file":"stress-300x261.jpg","width":300,"height":261,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/04\/stress-300x261.jpg"},"oneforthsquare":{"file":"stress-219x219.jpg","width":219,"height":219,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/04\/stress-219x219.jpg"},"onefifthsquare":{"file":"stress-168x168.jpg","width":168,"height":168,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/04\/stress-168x168.jpg"},"onesixthsquare":{"file":"stress-135x135.jpg","width":135,"height":135,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/04\/stress-135x135.jpg"},"onethirdlandscape":{"file":"stress-300x200.jpg","width":300,"height":200,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/04\/stress-300x200.jpg"},"oneforthlandscape":{"file":"stress-219x146.jpg","width":219,"height":146,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/04\/stress-219x146.jpg"},"onefifthlandscape":{"file":"stress-168x112.jpg","width":168,"height":112,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/04\/stress-168x112.jpg"},"onesixthlandscape":{"file":"stress-135x90.jpg","width":135,"height":90,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/04\/stress-135x90.jpg"},"onethirdportrait":{"file":"stress-300x261.jpg","width":300,"height":261,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/04\/stress-300x261.jpg"},"oneforthportrait":{"file":"stress-219x261.jpg","width":219,"height":261,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/04\/stress-219x261.jpg"},"onehalfsquare-inpost":{"file":"stress-305x261.jpg","width":305,"height":261,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/04\/stress-305x261.jpg"},"onethirdsquare-inpost":{"file":"stress-200x200.jpg","width":200,"height":200,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/04\/stress-200x200.jpg"},"oneforthsquare-inpost":{"file":"stress-145x145.jpg","width":145,"height":145,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/04\/stress-145x145.jpg"},"onehalflandscape-inpost":{"file":"stress-305x205.jpg","width":305,"height":205,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/04\/stress-305x205.jpg"},"onethirdlandscape-inpost":{"file":"stress-200x132.jpg","width":200,"height":132,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/04\/stress-200x132.jpg"},"oneforthlandscape-inpost":{"file":"stress-145x96.jpg","width":145,"height":96,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/04\/stress-145x96.jpg"},"onehalfportrait-inpost":{"file":"stress-305x261.jpg","width":305,"height":261,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/04\/stress-305x261.jpg"},"onethirdportrait-inpost":{"file":"stress-200x261.jpg","width":200,"height":261,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/04\/stress-200x261.jpg"},"oneforthportrait-inpost":{"file":"stress-145x193.jpg","width":145,"height":193,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/04\/stress-145x193.jpg"},"pensamentos":{"file":"stress-285x261.jpg","width":285,"height":261,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/04\/stress-285x261.jpg"},"categ":{"file":"stress-210x85.jpg","width":210,"height":85,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/04\/stress-210x85.jpg"}},"image_meta":{"aperture":0,"credit":"","camera":"","caption":"","created_timestamp":0,"copyright":"SolisImages - Fotolia","focal_length":0,"iso":0,"shutter_speed":0,"title":""}},"post":19266,"source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/04\/stress.jpg"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Sant\u00e9: \u00catre positif fait du bien \u00e0 la sant\u00e9! - Blog Viviane Freitas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.vivianefreitas.com\/fr\/2015\/04\/16\/sante-etre-positif-fait-du-bien-a-la-sante\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sant\u00e9: \u00catre positif fait du bien \u00e0 la sant\u00e9! - Blog Viviane Freitas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vivianefreitas.com\/fr\/2015\/04\/16\/sante-etre-positif-fait-du-bien-a-la-sante\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Viviane Freitas\" \/>\n<meta property=\"article:published_time\" content=\"2015-04-16T09:20:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vivianefreitas.com\/fr\/files\/2015\/04\/stress.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"660\" \/>\n\t<meta property=\"og:image:height\" content=\"261\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Viviane Freitas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Viviane Freitas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.vivianefreitas.com\/fr\/2015\/04\/16\/sante-etre-positif-fait-du-bien-a-la-sante\/\",\"url\":\"https:\/\/www.vivianefreitas.com\/fr\/2015\/04\/16\/sante-etre-positif-fait-du-bien-a-la-sante\/\",\"name\":\"Sant\u00e9: \u00catre positif fait du bien \u00e0 la sant\u00e9! - Blog Viviane Freitas\",\"isPartOf\":{\"@id\":\"https:\/\/www.vivianefreitas.com\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.vivianefreitas.com\/fr\/2015\/04\/16\/sante-etre-positif-fait-du-bien-a-la-sante\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.vivianefreitas.com\/fr\/2015\/04\/16\/sante-etre-positif-fait-du-bien-a-la-sante\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/04\/stress.jpg\",\"datePublished\":\"2015-04-16T09:20:14+00:00\",\"author\":{\"@id\":\"https:\/\/www.vivianefreitas.com\/fr\/#\/schema\/person\/da4a30407b47e202130ab7d6faa79cd0\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.vivianefreitas.com\/fr\/2015\/04\/16\/sante-etre-positif-fait-du-bien-a-la-sante\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.vivianefreitas.com\/fr\/2015\/04\/16\/sante-etre-positif-fait-du-bien-a-la-sante\/#primaryimage\",\"url\":\"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/04\/stress.jpg\",\"contentUrl\":\"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/04\/stress.jpg\",\"width\":660,\"height\":261},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.vivianefreitas.com\/fr\/#website\",\"url\":\"https:\/\/www.vivianefreitas.com\/fr\/\",\"name\":\"Blog Viviane Freitas\",\"description\":\"Bienvenue dans mon Blog\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.vivianefreitas.com\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.vivianefreitas.com\/fr\/#\/schema\/person\/da4a30407b47e202130ab7d6faa79cd0\",\"name\":\"Viviane Freitas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.vivianefreitas.com\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/718ec4eec1bf41a80d57ad6b6a8be8ab?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/718ec4eec1bf41a80d57ad6b6a8be8ab?s=96&d=mm&r=g\",\"caption\":\"Viviane Freitas\"},\"url\":\"https:\/\/www.vivianefreitas.com\/fr\/author\/viviane-freitas\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sant\u00e9: \u00catre positif fait du bien \u00e0 la sant\u00e9! - Blog Viviane Freitas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.vivianefreitas.com\/fr\/2015\/04\/16\/sante-etre-positif-fait-du-bien-a-la-sante\/","og_locale":"fr_FR","og_type":"article","og_title":"Sant\u00e9: \u00catre positif fait du bien \u00e0 la sant\u00e9! - Blog Viviane Freitas","og_url":"https:\/\/www.vivianefreitas.com\/fr\/2015\/04\/16\/sante-etre-positif-fait-du-bien-a-la-sante\/","og_site_name":"Blog Viviane Freitas","article_published_time":"2015-04-16T09:20:14+00:00","og_image":[{"width":660,"height":261,"url":"https:\/\/www.vivianefreitas.com\/fr\/files\/2015\/04\/stress.jpg","type":"image\/jpeg"}],"author":"Viviane Freitas","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Viviane Freitas","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.vivianefreitas.com\/fr\/2015\/04\/16\/sante-etre-positif-fait-du-bien-a-la-sante\/","url":"https:\/\/www.vivianefreitas.com\/fr\/2015\/04\/16\/sante-etre-positif-fait-du-bien-a-la-sante\/","name":"Sant\u00e9: \u00catre positif fait du bien \u00e0 la sant\u00e9! - Blog Viviane Freitas","isPartOf":{"@id":"https:\/\/www.vivianefreitas.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vivianefreitas.com\/fr\/2015\/04\/16\/sante-etre-positif-fait-du-bien-a-la-sante\/#primaryimage"},"image":{"@id":"https:\/\/www.vivianefreitas.com\/fr\/2015\/04\/16\/sante-etre-positif-fait-du-bien-a-la-sante\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/04\/stress.jpg","datePublished":"2015-04-16T09:20:14+00:00","author":{"@id":"https:\/\/www.vivianefreitas.com\/fr\/#\/schema\/person\/da4a30407b47e202130ab7d6faa79cd0"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vivianefreitas.com\/fr\/2015\/04\/16\/sante-etre-positif-fait-du-bien-a-la-sante\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vivianefreitas.com\/fr\/2015\/04\/16\/sante-etre-positif-fait-du-bien-a-la-sante\/#primaryimage","url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/04\/stress.jpg","contentUrl":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/04\/stress.jpg","width":660,"height":261},{"@type":"WebSite","@id":"https:\/\/www.vivianefreitas.com\/fr\/#website","url":"https:\/\/www.vivianefreitas.com\/fr\/","name":"Blog Viviane Freitas","description":"Bienvenue dans mon Blog","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vivianefreitas.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.vivianefreitas.com\/fr\/#\/schema\/person\/da4a30407b47e202130ab7d6faa79cd0","name":"Viviane Freitas","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vivianefreitas.com\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/718ec4eec1bf41a80d57ad6b6a8be8ab?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/718ec4eec1bf41a80d57ad6b6a8be8ab?s=96&d=mm&r=g","caption":"Viviane Freitas"},"url":"https:\/\/www.vivianefreitas.com\/fr\/author\/viviane-freitas\/"}]}},"jetpack_featured_media_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/04\/stress.jpg","_links":{"self":[{"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/posts\/19266","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/comments?post=19266"}],"version-history":[{"count":1,"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/posts\/19266\/revisions"}],"predecessor-version":[{"id":19268,"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/posts\/19266\/revisions\/19268"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/media\/19267"}],"wp:attachment":[{"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/media?parent=19266"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/categories?post=19266"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/tags?post=19266"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}