{"id":19186,"date":"2015-04-03T09:01:43","date_gmt":"2015-04-03T09:01:43","guid":{"rendered":"http:\/\/www.vivianefreitas.com\/fr\/?p=19186"},"modified":"2015-04-03T09:01:43","modified_gmt":"2015-04-03T09:01:43","slug":"organisation-limites-et-correction","status":"publish","type":"post","link":"https:\/\/www.vivianefreitas.com\/fr\/2015\/04\/03\/organisation-limites-et-correction\/","title":{"rendered":"Organisation, limites et correction"},"content":{"rendered":"<p><p class=\"intro\">La premi\u00e8re chose que j&rsquo;ai appris au sujet de l&rsquo;autisme c&rsquo;est que mon fils avait besoin d\u2019organisation. Il avait le besoin de se sentir en s\u00e9curit\u00e9 et cela ne serait possible que s&rsquo;il savait ce qui se passerait dans sa journ\u00e9e.<\/p><br \/>\n<!--more--><\/p>\n<p>Aujourd&rsquo;hui, je pense que tout enfant a besoin d&rsquo;un jour organis\u00e9, avec des limites et des horaires, afin qu&rsquo;il puisse grandir d&rsquo;une mani\u00e8re saine et respectueuse, \u00e0 savoir l&rsquo;espace de chacun dans la soci\u00e9t\u00e9.<\/p>\n<p>Si tous les \u00eatres humains ont besoin de limites, de r\u00e8gles \u00e0 suivre, d&rsquo;instructions et de conseils pour ne pas se perdre, imaginez un enfant?<br \/>\nGrandir sans tout cela, ferait devenir certainement un jeune et peut-\u00eatre un adulte incoh\u00e9rent, avec la pens\u00e9e qu&rsquo;il peut faire tout de la fa\u00e7on et au moment qu&rsquo;il le veut, sans qu&rsquo;il ne sache pas respecter les autorit\u00e9s, sans qu&rsquo;il ne r\u00e9ussisse \u00e0 se soumettre aux normes &#8230; C&rsquo;est-t&rsquo;\u00e0-dire, il aurait du mal \u00e0 travailler dans n&rsquo;importe quelle entreprise, de suivre Dieu, de recevoir des conseils afin de construire une famille, enfin en tout ce qu&rsquo;il voudrait faire. Parce que, pour lui, tout est toujours en d\u00e9sordre, et cette erreur aurait commenc\u00e9 bien avant, dans une enfance d\u00e9sordonn\u00e9e et sans limites. Ce n&rsquo;est rien de ce que nous souhaitons pour nos enfants, n&rsquo;est-ce pas?<\/p>\n<p>Donc, nous allons commencer d\u00e8s maintenant \u00e0 changer nos vies, afin que nous puissions prendre des dispositions pour leur apprendre \u00e0 s&rsquo;organiser. Sachez que \u00ab\u00a0le manque d\u2019organisation\u00a0\u00bb, montre le manque de vie, d&rsquo;intimit\u00e9 avec Dieu\u00a0\u00bb !<br \/>\nTout le Royaume de Dieu et Son oeuvre et ordonn\u00e9 et pour faire partie de celui-ci nous devons \u00eatre organis\u00e9es.<\/p>\n<p><strong>Alors voici quelques conseils d&rsquo;organisation pour vous:<\/strong><\/p>\n<p>&#8211; \u00e9laborer un planning hebdomadaire, avant que la semaine ne commence, \u00e9crivez sur votre planning tout ce que vous avez \u00e0 faire, y compris le temps pour vos enfants;<br \/>\n*Je le fais et j&rsquo;ai \u00e9galement un tableau mensuel sur la porte de mon frigo, o\u00f9 je note les engagements de toute la famille, afin que personne n&rsquo;oublie, ainsi l&rsquo;un rappel l&rsquo;autre.<\/p>\n<p>&#8211; Levez-vous un peu plus t\u00f4t pour prendre soin de vous, lire la parole de Dieu et de faire votre premi\u00e8re pri\u00e8re pendant que tous dorment encore. Croyez-moi, ces quelques minutes vont faire toute la diff\u00e9rence dans votre vie et dans celle de votre famille, car cela vous \u00e9vitera de prendre de mauvaises attitudes. T\u00f4t le matin, tous auront \u00e0 la maison une maman tranquille et remplie du Saint-Esprit, ceci les dirigera et les b\u00e9nira pour commencer une nouvelle journ\u00e9e de batailles;<\/p>\n<p>&#8211; Autant que possible, ayez des repas de famille, o\u00f9 chacun s&rsquo;assoit \u00e0 la table, prient ensemble et ont cette convivialit\u00e9;<\/p>\n<p>&#8211; Profitez du temps que vos enfants sont \u00e0 l\u2019\u00e9cole, pour faire votre travail et vos activit\u00e9s, de sorte que lorsqu&rsquo;ils seront libres, vous pourriez leur donner de l&rsquo;attention;<\/p>\n<p>&#8211; S\u00e9parez uniquement quelques obligations quotidiennes. Eh oui, vous pouvez faire tout cela et encore avoir un peu de temps pour vous, pour faire quelque chose que vous aimez et que vous d&rsquo;\u00e9tend, m\u00eame si c&rsquo;est une fois par semaine;<\/p>\n<p>&#8211; \u00catre toujours attentif aux devoirs de l&rsquo;\u00e9cole et en contact avec les enseignants pour savoir comment votre enfant est en classe, le comportement dans la recr\u00e9e, etc.<br \/>\n* Une m\u00e8re attentive peut mieux \u00e9duquer et conseiller avant m\u00eame que les probl\u00e8mes surgissent.<\/p>\n<p>&#8211; Superviser toujours l&rsquo;internet et le t\u00e9l\u00e9phone!<\/p>\n<p> &#8211; Ne devancez jamais l&rsquo;autorit\u00e9 de votre \u00e9poux face aux enfants, m\u00eame s&rsquo;il a tort. Si cela, c&rsquo;est le cas, que votre \u00e9poux agisse mal, parlez-en avec lui seul et laissez-le lui-m\u00eame corriger son erreur. Enseignez vos enfants \u00e0 le respecter, parce que s&rsquo;ils sauront respecter le p\u00e8re qu&rsquo;ils voient, ils sauront respecter Dieu le P\u00e8re qu\u2019ils ne voient pas;<\/p>\n<p>&#8211; Mettre en place l&rsquo;horaire d&rsquo;aller au lit pour dormir. De fa\u00e7on, que vous avez une heure chaque jour pour vous et votre mari;<\/p>\n<p>&#8211; A la fin de la journ\u00e9e, il est tr\u00e8s important de les mettre au lit, lire un verset avec eux, parler et m\u00e9diter ensemble sur lui, prier et imposer la main sur vos enfants, afin de les b\u00e9nir. Dieu vous a donn\u00e9 ce pouvoir et c&rsquo;est \u00e0 vous de l&rsquo;exercer.<\/p>\n<p><strong>Maintenant, quelques conseils d&rsquo;organisation pour vos enfants:<\/strong><\/p>\n<p>&#8211; organisez leur semaine, notez l&rsquo;horaire du coucher, du lever et des repas;<\/p>\n<p>&#8211; apr\u00e8s un certain \u00e2ge, il doit prendre soin de sa chambre;<\/p>\n<p>&#8211; De l&rsquo;ordre avec ses horaires et ses activit\u00e9s, \u00e0 savoir, d&rsquo;abord les obligations et puis le plaisir;<\/p>\n<p>&#8211; TV, jeux, \u00abjeu vid\u00e9o\u00bb et Internet, vous devez \u00eatre toujours attentif \u00e0 tout ce qu&rsquo;il sera en train de voir, de faire, et \u00e9tablissez que quelques fois par semaine une dur\u00e9e de deux heures au maximum;<br \/>\n* Mon fils joue son \u00ab\u00a0jeu vid\u00e9o\u00a0\u00bb seulement une fois par semaine et deux heures sur Internet, il ne fait pas de recherches sur internet tout seul, il entre dans le site \u00e0 l&rsquo;\u00e9cole pour faire les devoirs et visualise des vid\u00e9os pour enfants comme \u00ab la classe de la foi \u00bb (de la petite \u00e9cole biblique), cela pour deux heures et avec moi, mes oreilles restent attentives. Je n&rsquo;utilise pas ces moyens pour occuper mon fils, afin que je puisse faire mes affaires.<\/p>\n<p>&#8211; L&rsquo;activit\u00e9 sportive est toujours tr\u00e8s importante pour le d\u00e9veloppement de l&rsquo;enfant, parce que dans le sport il d\u00e9pense les \u00e9nergies n\u00e9cessaires, ainsi il ne grandit pas avec une vie s\u00e9dentaire. Ils apprendront des r\u00e8gles et \u00e0 penser au groupe, ainsi ils perdent leur individualisme. Il serait tr\u00e8s bien si vous pouviez y assister au moins deux fois par semaine;<\/p>\n<p>&#8211; L&rsquo;enfant a besoin de jours \u00e0 \u00e9cole, de jours \u00e0 \u00e9glise et de jours avec les parents, la famille. Ces trois rencontres sont la base pour une croissance saine et doivent \u00eatre sur leur planning hebdomadaire;<\/p>\n<p>&#8211; Jouer avec leurs amis dans la rue ou dans le b\u00e2timent sans les soins d&rsquo;un adulte, JAMAIS de la vie ! Les enfants n&rsquo;ont aucune responsabilit\u00e9 ou sentiment du danger, et encore moins la condition de prendre soin d&rsquo;eux-m\u00eames, donc les enfants doivent \u00eatre trait\u00e9s et surveill\u00e9s en tant que tels;<br \/>\n* Mon fils joue avec leurs amis ici \u00e0 la maison. Nous avons \u00e9tabli un apr\u00e8s-midi par semaine, afin qu&rsquo;il puisse inviter un ami, jouer sur ma surveillance et toujours profiter l&rsquo;occasion pour enseigner quelque chose \u00e0 Gabi \u00e0 travers le jeu. Si possible, je l&rsquo;am\u00e8ne dans un terrain de jeu ou \u00e0 la piscine. Et il ne peut aller que dans la maison de trois amis que je connais les familles et que je suis certaine que l\u00e0-bas ils vont jouer sur la surveillance de leurs mamans.<\/p>\n<p>&#8211; Pertes: tr\u00e8s t\u00f4t ils doivent apprendre que les mauvaises attitudes g\u00e9n\u00e8rent toujours des dommages, m\u00eame s&rsquo;ils se font pardonner, ils souffriront les mauvais fruits de cette erreur.<\/p>\n<p>Ce ne sont que quelques conseils que nous utilisons ici \u00e0 la maison, que nous ont beaucoup aid\u00e9s, mais ceci n&rsquo;est pas une imposition, ok?!<\/p>\n<p>Peut-\u00eatre que vous avez trouv\u00e9 un peu exag\u00e9r\u00e9, mais si vous ne fixez pas de limites sur la vie de votre enfant, d\u00e8s leur enfance, la vie et le mal s\u2019en occuperont de le faire et vous pouvez \u00eatre s\u00fbr, de la pire fa\u00e7on!<\/p>\n<p>Je vous pose la question: \u00abS&rsquo;il n&rsquo;y a pas de r\u00e8gles et de limites, comment pourrez-vous les corrig\u00e9s?\u00a0\u00bb Plusieurs mamans me demandent quelle est la bonne fa\u00e7on de corriger un enfant et je leur r\u00e9ponds: \u00abLa meilleure fa\u00e7on se trouve dans la parole de Dieu.\u00a0\u00bb<\/p>\n<p>Nous en reparlerons la semaine prochaine &#8230; Mais pour commencer, nous devrions imposer de r\u00e8gles et de limites en sorte que nous puissions corriger lors du non-respect envers l&rsquo;un d&rsquo;eux.<\/p>\n<p>Les limites doivent commencer \u00e0 la maison, doivent \u00eatre discut\u00e9es et misent en place par les parents.<\/p>\n<p>Nous esp\u00e9rons vous avoir aid\u00e9, nous nous retrouverons la semaine prochaine.<\/p>\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":4,"featured_media":19201,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[29,1],"tags":[],"class_list":["post-19186","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-de-mere-pour-mere-josiane-boccoli-categories","category-non-categorise"],"better_featured_image":{"id":19201,"alt_text":"","caption":"","description":"","media_type":"image","media_details":{"width":660,"height":260,"file":"2015\/03\/CORRECTKIDS.jpg","sizes":{"thumbnail":{"file":"CORRECTKIDS-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/03\/CORRECTKIDS-150x150.jpg"},"medium":{"file":"CORRECTKIDS-300x118.jpg","width":300,"height":118,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/03\/CORRECTKIDS-300x118.jpg"},"blogintro":{"file":"CORRECTKIDS-144x100.jpg","width":144,"height":100,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/03\/CORRECTKIDS-144x100.jpg"},"onethirdsquare":{"file":"CORRECTKIDS-300x260.jpg","width":300,"height":260,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/03\/CORRECTKIDS-300x260.jpg"},"oneforthsquare":{"file":"CORRECTKIDS-219x219.jpg","width":219,"height":219,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/03\/CORRECTKIDS-219x219.jpg"},"onefifthsquare":{"file":"CORRECTKIDS-168x168.jpg","width":168,"height":168,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/03\/CORRECTKIDS-168x168.jpg"},"onesixthsquare":{"file":"CORRECTKIDS-135x135.jpg","width":135,"height":135,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/03\/CORRECTKIDS-135x135.jpg"},"onethirdlandscape":{"file":"CORRECTKIDS-300x200.jpg","width":300,"height":200,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/03\/CORRECTKIDS-300x200.jpg"},"oneforthlandscape":{"file":"CORRECTKIDS-219x146.jpg","width":219,"height":146,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/03\/CORRECTKIDS-219x146.jpg"},"onefifthlandscape":{"file":"CORRECTKIDS-168x112.jpg","width":168,"height":112,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/03\/CORRECTKIDS-168x112.jpg"},"onesixthlandscape":{"file":"CORRECTKIDS-135x90.jpg","width":135,"height":90,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/03\/CORRECTKIDS-135x90.jpg"},"onethirdportrait":{"file":"CORRECTKIDS-300x260.jpg","width":300,"height":260,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/03\/CORRECTKIDS-300x260.jpg"},"oneforthportrait":{"file":"CORRECTKIDS-219x260.jpg","width":219,"height":260,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/03\/CORRECTKIDS-219x260.jpg"},"onehalfsquare-inpost":{"file":"CORRECTKIDS-305x260.jpg","width":305,"height":260,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/03\/CORRECTKIDS-305x260.jpg"},"onethirdsquare-inpost":{"file":"CORRECTKIDS-200x200.jpg","width":200,"height":200,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/03\/CORRECTKIDS-200x200.jpg"},"oneforthsquare-inpost":{"file":"CORRECTKIDS-145x145.jpg","width":145,"height":145,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/03\/CORRECTKIDS-145x145.jpg"},"onehalflandscape-inpost":{"file":"CORRECTKIDS-305x205.jpg","width":305,"height":205,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/03\/CORRECTKIDS-305x205.jpg"},"onethirdlandscape-inpost":{"file":"CORRECTKIDS-200x132.jpg","width":200,"height":132,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/03\/CORRECTKIDS-200x132.jpg"},"oneforthlandscape-inpost":{"file":"CORRECTKIDS-145x96.jpg","width":145,"height":96,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/03\/CORRECTKIDS-145x96.jpg"},"onehalfportrait-inpost":{"file":"CORRECTKIDS-305x260.jpg","width":305,"height":260,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/03\/CORRECTKIDS-305x260.jpg"},"onethirdportrait-inpost":{"file":"CORRECTKIDS-200x260.jpg","width":200,"height":260,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/03\/CORRECTKIDS-200x260.jpg"},"oneforthportrait-inpost":{"file":"CORRECTKIDS-145x193.jpg","width":145,"height":193,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/03\/CORRECTKIDS-145x193.jpg"},"pensamentos":{"file":"CORRECTKIDS-285x260.jpg","width":285,"height":260,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/03\/CORRECTKIDS-285x260.jpg"},"categ":{"file":"CORRECTKIDS-210x85.jpg","width":210,"height":85,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/03\/CORRECTKIDS-210x85.jpg"}},"image_meta":{"aperture":0,"credit":"","camera":"","caption":"","created_timestamp":0,"copyright":"","focal_length":0,"iso":0,"shutter_speed":0,"title":""}},"post":19186,"source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/03\/CORRECTKIDS.jpg"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Organisation, limites et correction - Blog Viviane Freitas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.vivianefreitas.com\/fr\/2015\/04\/03\/organisation-limites-et-correction\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Organisation, limites et correction - Blog Viviane Freitas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vivianefreitas.com\/fr\/2015\/04\/03\/organisation-limites-et-correction\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Viviane Freitas\" \/>\n<meta property=\"article:published_time\" content=\"2015-04-03T09:01:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vivianefreitas.com\/fr\/files\/2015\/03\/CORRECTKIDS.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"660\" \/>\n\t<meta property=\"og:image:height\" content=\"260\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Viviane Freitas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Viviane Freitas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.vivianefreitas.com\/fr\/2015\/04\/03\/organisation-limites-et-correction\/\",\"url\":\"https:\/\/www.vivianefreitas.com\/fr\/2015\/04\/03\/organisation-limites-et-correction\/\",\"name\":\"Organisation, limites et correction - Blog Viviane Freitas\",\"isPartOf\":{\"@id\":\"https:\/\/www.vivianefreitas.com\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.vivianefreitas.com\/fr\/2015\/04\/03\/organisation-limites-et-correction\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.vivianefreitas.com\/fr\/2015\/04\/03\/organisation-limites-et-correction\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/03\/CORRECTKIDS.jpg\",\"datePublished\":\"2015-04-03T09:01:43+00:00\",\"author\":{\"@id\":\"https:\/\/www.vivianefreitas.com\/fr\/#\/schema\/person\/da4a30407b47e202130ab7d6faa79cd0\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.vivianefreitas.com\/fr\/2015\/04\/03\/organisation-limites-et-correction\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.vivianefreitas.com\/fr\/2015\/04\/03\/organisation-limites-et-correction\/#primaryimage\",\"url\":\"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/03\/CORRECTKIDS.jpg\",\"contentUrl\":\"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/03\/CORRECTKIDS.jpg\",\"width\":660,\"height\":260},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.vivianefreitas.com\/fr\/#website\",\"url\":\"https:\/\/www.vivianefreitas.com\/fr\/\",\"name\":\"Blog Viviane Freitas\",\"description\":\"Bienvenue dans mon Blog\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.vivianefreitas.com\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.vivianefreitas.com\/fr\/#\/schema\/person\/da4a30407b47e202130ab7d6faa79cd0\",\"name\":\"Viviane Freitas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.vivianefreitas.com\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/718ec4eec1bf41a80d57ad6b6a8be8ab?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/718ec4eec1bf41a80d57ad6b6a8be8ab?s=96&d=mm&r=g\",\"caption\":\"Viviane Freitas\"},\"url\":\"https:\/\/www.vivianefreitas.com\/fr\/author\/viviane-freitas\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Organisation, limites et correction - Blog Viviane Freitas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.vivianefreitas.com\/fr\/2015\/04\/03\/organisation-limites-et-correction\/","og_locale":"fr_FR","og_type":"article","og_title":"Organisation, limites et correction - Blog Viviane Freitas","og_url":"https:\/\/www.vivianefreitas.com\/fr\/2015\/04\/03\/organisation-limites-et-correction\/","og_site_name":"Blog Viviane Freitas","article_published_time":"2015-04-03T09:01:43+00:00","og_image":[{"width":660,"height":260,"url":"https:\/\/www.vivianefreitas.com\/fr\/files\/2015\/03\/CORRECTKIDS.jpg","type":"image\/jpeg"}],"author":"Viviane Freitas","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Viviane Freitas","Dur\u00e9e de lecture estim\u00e9e":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.vivianefreitas.com\/fr\/2015\/04\/03\/organisation-limites-et-correction\/","url":"https:\/\/www.vivianefreitas.com\/fr\/2015\/04\/03\/organisation-limites-et-correction\/","name":"Organisation, limites et correction - Blog Viviane Freitas","isPartOf":{"@id":"https:\/\/www.vivianefreitas.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vivianefreitas.com\/fr\/2015\/04\/03\/organisation-limites-et-correction\/#primaryimage"},"image":{"@id":"https:\/\/www.vivianefreitas.com\/fr\/2015\/04\/03\/organisation-limites-et-correction\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/03\/CORRECTKIDS.jpg","datePublished":"2015-04-03T09:01:43+00:00","author":{"@id":"https:\/\/www.vivianefreitas.com\/fr\/#\/schema\/person\/da4a30407b47e202130ab7d6faa79cd0"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vivianefreitas.com\/fr\/2015\/04\/03\/organisation-limites-et-correction\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vivianefreitas.com\/fr\/2015\/04\/03\/organisation-limites-et-correction\/#primaryimage","url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/03\/CORRECTKIDS.jpg","contentUrl":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/03\/CORRECTKIDS.jpg","width":660,"height":260},{"@type":"WebSite","@id":"https:\/\/www.vivianefreitas.com\/fr\/#website","url":"https:\/\/www.vivianefreitas.com\/fr\/","name":"Blog Viviane Freitas","description":"Bienvenue dans mon Blog","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vivianefreitas.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.vivianefreitas.com\/fr\/#\/schema\/person\/da4a30407b47e202130ab7d6faa79cd0","name":"Viviane Freitas","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vivianefreitas.com\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/718ec4eec1bf41a80d57ad6b6a8be8ab?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/718ec4eec1bf41a80d57ad6b6a8be8ab?s=96&d=mm&r=g","caption":"Viviane Freitas"},"url":"https:\/\/www.vivianefreitas.com\/fr\/author\/viviane-freitas\/"}]}},"jetpack_featured_media_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2015\/03\/CORRECTKIDS.jpg","_links":{"self":[{"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/posts\/19186","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/comments?post=19186"}],"version-history":[{"count":2,"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/posts\/19186\/revisions"}],"predecessor-version":[{"id":19203,"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/posts\/19186\/revisions\/19203"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/media\/19201"}],"wp:attachment":[{"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/media?parent=19186"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/categories?post=19186"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/tags?post=19186"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}