{"id":18861,"date":"2014-11-29T09:00:43","date_gmt":"2014-11-29T09:00:43","guid":{"rendered":"http:\/\/www.vivianefreitas.com\/fr\/?p=18861"},"modified":"2014-12-03T16:21:36","modified_gmt":"2014-12-03T16:21:36","slug":"le-jour-que-je-nai-pas-entree-dans-le-godllywood","status":"publish","type":"post","link":"https:\/\/www.vivianefreitas.com\/fr\/2014\/11\/29\/le-jour-que-je-nai-pas-entree-dans-le-godllywood\/","title":{"rendered":"Exp\u00e9rience: Le jour que je n\u2019ai pas entr\u00e9e dans le Godllywood"},"content":{"rendered":"<p><p class=\"intro\">Ne pensez pas que, comme vous \u00eates en train de construire une relation avec Dieu, et vous cherchez que votre vie soit encadr\u00e9e dans Sa parole, que tout maintenant va devenir un lit e roses, ainsi c\u2019\u00e9tait bon, rsrsrs.<\/p><br \/>\n<!--more--><br \/>\nPr\u00e9parez-vous les d\u00e9fis viendront,\u00a0en fait, ils existaient d\u00e9j\u00e0 dans votre vie, la diff\u00e9rence est que, lorsque nous sommes s\u00e9par\u00e9es de Dieu, nous voyons le poids et les difficult\u00e9s mais, une fois attach\u00e9e \u00e0 Lui, tout devient une OPORTUNITE.<\/p>\n<p>Bon, tout ce que je vous avais dit dans les post pr\u00e9c\u00e9dents, est arriv\u00e9 en Espagne,\u00a0quand je suis arriv\u00e9e et je suis tomb\u00e9e sur une r\u00e9alit\u00e9\u00a0: mon mari \u00e9tait un leader, et moi une ombre\u2026 (Je vous conseille de suivre les messages hebdomadaires) pour comprendre l\u2019histoire, car ma vie, est similaire \u00e0 la majorit\u00e9 des femmes dans l\u2019\u00e9glise, parfois, semble m\u00eame une s\u00e9rie).<\/p>\n<p>Eh bien, ont continue\u2026 Qu\u2019est ce qui est arriv\u00e9 suite \u00e0 mes premi\u00e8res d\u00e9couvertes\u00a0?<\/p>\n<p>Revenons un peu dans le temps, pour que je vous raconte un autre d\u00e9tail \u00e0 propos de ce qui est arriv\u00e9\u2026<\/p>\n<p>A la fin de 2009, j\u2019ai entendu parler au surgissement du Godllywood (http:\/\/www.godllywood.com\/pt\/), j\u2019\u00e9tais ravie du travail, l\u2019id\u00e9e de pouvoir aider les filles et les femmes de l\u2019\u00e9glise m\u2019a rempli de d\u00e9sir de faire partie de ce travail.<\/p>\n<p>Dans le mois suivant, j\u2019ai \u00e9t\u00e9 transf\u00e9r\u00e9e \u00e0 l\u2019Espagne, et l\u00e0 le groupe n\u2019existait pas encore, donc, je devrais attendre le jour qu\u2019il aura.<br \/>\nJe suivais par internet, tout ce qui se passait, et en priant pour que bient\u00f4t nous puissions avoir cet opportunit\u00e9. Parall\u00e8lement \u00e0 cela, je passais pour toutes ces d\u00e9couvertes, que je vous avais dit.<\/p>\n<p>Les mois pass\u00e8rent, et finalement le jour tant attendu est arriv\u00e9, l\u2019\u00e9pouse du leader est venue nous rendre visite et avec elle une grande nouvelle\u00a0: Le Godllywood va commencer en Espagne!!!<\/p>\n<p>Mon c\u0153ur se sentait comme s\u2019il all\u00e9 sortir de ma bouche autant de joie, mais, d\u2019une seconde \u00e0 l\u2019autre, c\u2019\u00e9tait comme si le ciel s\u2019assombrit, elle a dit que le groupe all\u00e9 commencer, oui, mais une autre \u00e9pouse serait responsable pour lui, ok, jusqu\u2019ici \u00e7a va, j\u2019ai pris courage et j\u2019ai demand\u00e9e\u00a0: \u00ab\u00a0&#8211; Bon, mais, je vais pouvoir aider\u00a0?\u00a0\u00bb<br \/>\n\u00ab\u00a0&#8211; Non! Ce travail est tr\u00e8s s\u00e9rieux, et je ne vous connais pas assez, alors vous ne pouvez m\u00eame pas aider\u00a0\u00bb. C\u2019\u00e9tait la r\u00e9ponse directe au point que j\u2019ai re\u00e7ue\u2026<\/p>\n<p>J\u2019avais d\u00e9j\u00e0 travaill\u00e9e avec elle au Portugal, et comme \u00e0 l\u2019\u00e9poque je vivais limit\u00e9e par la timidit\u00e9, l\u2019ins\u00e9curit\u00e9, etc., jamais je me suis fait connaitre.<br \/>\nJe sentais mon visage br\u00fbler, \u00e0 partir de l\u00e0, c\u2019\u00e9tais comme si je n\u2019entendais plus rien, j\u2019ai la laiss\u00e9e \u00e0 l\u2019a\u00e9roport et je suis partie, ce jour j\u2019ai pas voulu retourner \u00e0 l\u2019\u00e9glise, j\u2019avais besoin de rentrer chez moi, \u00eatre seule, j\u2019avais un sujet tr\u00e8s s\u00e9rieux pour r\u00e9soudre avec Dieu.<br \/>\nChaque fois que j\u2019ai une question tr\u00e8s difficile, je besoin d\u2019\u00eatre seule avec Lui, l\u2019Entendre, savoir qu\u2019elle est Sa volont\u00e9 et qu\u2019est ce qu\u2019Il veut m\u2019apprendre \u00e0 travers de ce que je suis en train de vivre.<\/p>\n<p>Pourquoi mon Dieu\u00a0?! je voulais tellement pouvoir aider les gens, vu que je travaille d\u00e9j\u00e0 avec les jeune filles, r\u00eaver d\u2019appartenir \u00e0 ce groupe et \u00eatre plus utilis\u00e9e par le Seigneur, et maintenant \u00e7a\u00a0?! Le Seigneur me dit non\u00a0!!!<br \/>\nJe n\u2019ai jamais vu ce non comme quelque chose personnelle, ou venant de mon leader, je savais que Dieu \u00e9tait dans le contr\u00f4le de tout, mais je ne comprenais pas pourquoi.<\/p>\n<p>Ce n\u2019est pas ainsi dont vous vous voyez souvent, cher lectrice\u00a0? Vos intentions sont apparemment les meilleurs possibles, vous travaillez dur, sacrifiant m\u00eame, et d\u2019en cou  il semble ce fut en vain, personne ne voit pas combien vous avez combattu pour cela\u00a0?<\/p>\n<p>Je ne comprenais pas, alors mon \u00e9poux \u00e9tait l\u00e0 comme leader, chaque fois je voyais Dieu compter sur lui de plus en plus et moi\u00a0? Pourquoi je ne pouvais pas \u00eatre utilis\u00e9e\u00a0?<\/p>\n<p>Et encore, si tant de chose si passait \u00e0 l\u2019int\u00e9rieur de moi, pourquoi maintenant ce non\u00a0?!<\/p>\n<p>Je ne comprenais pas pourquoi tout cela si passait.<\/p>\n<p>Depuis quelque temps, dans cette longue nuit, J\u2019ai r\u00e9ussie \u00e0 garder les larmes et la douleur profonde que je sentais en moi, puis jusqu\u2019ici, juste moi parlais et interrogeais, et il n\u2019y avait pas de r\u00e9ponses, alors quand je me suis s\u00e9par\u00e9e du sentiment, Dieu a commenc\u00e9 \u00e0 parler avec moi, et m\u2019a r\u00e9pondu \u00e0 cette question.<\/p>\n<p>C\u2019\u00e9tait l\u2019une des r\u00e9ponses les plus difficiles que j\u2019ai eu jusqu\u2019au aujourd\u2019hui, je ne pouvais jamais imaginer entendre une telle chose.<\/p>\n<p>Dans le prochain post, je continue\u2026<\/p>\n<p>Je vous embrasse et \u00e0 bient\u00f4t\u00a0!<\/p>\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":4,"featured_media":18862,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-18861","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-relation-patricia-b"],"better_featured_image":{"id":18862,"alt_text":"","caption":"","description":"","media_type":"image","media_details":{"width":660,"height":261,"file":"2014\/11\/nao_entrei_godllywood.jpg","sizes":{"thumbnail":{"file":"nao_entrei_godllywood-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/11\/nao_entrei_godllywood-150x150.jpg"},"medium":{"file":"nao_entrei_godllywood-300x118.jpg","width":300,"height":118,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/11\/nao_entrei_godllywood-300x118.jpg"},"blogintro":{"file":"nao_entrei_godllywood-144x100.jpg","width":144,"height":100,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/11\/nao_entrei_godllywood-144x100.jpg"},"onethirdsquare":{"file":"nao_entrei_godllywood-300x261.jpg","width":300,"height":261,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/11\/nao_entrei_godllywood-300x261.jpg"},"oneforthsquare":{"file":"nao_entrei_godllywood-219x219.jpg","width":219,"height":219,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/11\/nao_entrei_godllywood-219x219.jpg"},"onefifthsquare":{"file":"nao_entrei_godllywood-168x168.jpg","width":168,"height":168,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/11\/nao_entrei_godllywood-168x168.jpg"},"onesixthsquare":{"file":"nao_entrei_godllywood-135x135.jpg","width":135,"height":135,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/11\/nao_entrei_godllywood-135x135.jpg"},"onethirdlandscape":{"file":"nao_entrei_godllywood-300x200.jpg","width":300,"height":200,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/11\/nao_entrei_godllywood-300x200.jpg"},"oneforthlandscape":{"file":"nao_entrei_godllywood-219x146.jpg","width":219,"height":146,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/11\/nao_entrei_godllywood-219x146.jpg"},"onefifthlandscape":{"file":"nao_entrei_godllywood-168x112.jpg","width":168,"height":112,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/11\/nao_entrei_godllywood-168x112.jpg"},"onesixthlandscape":{"file":"nao_entrei_godllywood-135x90.jpg","width":135,"height":90,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/11\/nao_entrei_godllywood-135x90.jpg"},"onethirdportrait":{"file":"nao_entrei_godllywood-300x261.jpg","width":300,"height":261,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/11\/nao_entrei_godllywood-300x261.jpg"},"oneforthportrait":{"file":"nao_entrei_godllywood-219x261.jpg","width":219,"height":261,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/11\/nao_entrei_godllywood-219x261.jpg"},"onehalfsquare-inpost":{"file":"nao_entrei_godllywood-305x261.jpg","width":305,"height":261,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/11\/nao_entrei_godllywood-305x261.jpg"},"onethirdsquare-inpost":{"file":"nao_entrei_godllywood-200x200.jpg","width":200,"height":200,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/11\/nao_entrei_godllywood-200x200.jpg"},"oneforthsquare-inpost":{"file":"nao_entrei_godllywood-145x145.jpg","width":145,"height":145,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/11\/nao_entrei_godllywood-145x145.jpg"},"onehalflandscape-inpost":{"file":"nao_entrei_godllywood-305x205.jpg","width":305,"height":205,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/11\/nao_entrei_godllywood-305x205.jpg"},"onethirdlandscape-inpost":{"file":"nao_entrei_godllywood-200x132.jpg","width":200,"height":132,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/11\/nao_entrei_godllywood-200x132.jpg"},"oneforthlandscape-inpost":{"file":"nao_entrei_godllywood-145x96.jpg","width":145,"height":96,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/11\/nao_entrei_godllywood-145x96.jpg"},"onehalfportrait-inpost":{"file":"nao_entrei_godllywood-305x261.jpg","width":305,"height":261,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/11\/nao_entrei_godllywood-305x261.jpg"},"onethirdportrait-inpost":{"file":"nao_entrei_godllywood-200x261.jpg","width":200,"height":261,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/11\/nao_entrei_godllywood-200x261.jpg"},"oneforthportrait-inpost":{"file":"nao_entrei_godllywood-145x193.jpg","width":145,"height":193,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/11\/nao_entrei_godllywood-145x193.jpg"},"pensamentos":{"file":"nao_entrei_godllywood-285x261.jpg","width":285,"height":261,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/11\/nao_entrei_godllywood-285x261.jpg"},"categ":{"file":"nao_entrei_godllywood-210x85.jpg","width":210,"height":85,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/11\/nao_entrei_godllywood-210x85.jpg"}},"image_meta":{"aperture":0,"credit":"","camera":"","caption":"","created_timestamp":0,"copyright":"DragonImages - Fotolia","focal_length":0,"iso":0,"shutter_speed":0,"title":""}},"post":18861,"source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/11\/nao_entrei_godllywood.jpg"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Exp\u00e9rience: Le jour que je n\u2019ai pas entr\u00e9e dans le Godllywood - Blog Viviane Freitas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.vivianefreitas.com\/fr\/2014\/11\/29\/le-jour-que-je-nai-pas-entree-dans-le-godllywood\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Exp\u00e9rience: Le jour que je n\u2019ai pas entr\u00e9e dans le Godllywood - Blog Viviane Freitas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vivianefreitas.com\/fr\/2014\/11\/29\/le-jour-que-je-nai-pas-entree-dans-le-godllywood\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Viviane Freitas\" \/>\n<meta property=\"article:published_time\" content=\"2014-11-29T09:00:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2014-12-03T16:21:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vivianefreitas.com\/fr\/files\/2014\/11\/nao_entrei_godllywood.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"660\" \/>\n\t<meta property=\"og:image:height\" content=\"261\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Viviane Freitas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Viviane Freitas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.vivianefreitas.com\/fr\/2014\/11\/29\/le-jour-que-je-nai-pas-entree-dans-le-godllywood\/\",\"url\":\"https:\/\/www.vivianefreitas.com\/fr\/2014\/11\/29\/le-jour-que-je-nai-pas-entree-dans-le-godllywood\/\",\"name\":\"Exp\u00e9rience: Le jour que je n\u2019ai pas entr\u00e9e dans le Godllywood - Blog Viviane Freitas\",\"isPartOf\":{\"@id\":\"https:\/\/www.vivianefreitas.com\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.vivianefreitas.com\/fr\/2014\/11\/29\/le-jour-que-je-nai-pas-entree-dans-le-godllywood\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.vivianefreitas.com\/fr\/2014\/11\/29\/le-jour-que-je-nai-pas-entree-dans-le-godllywood\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/11\/nao_entrei_godllywood.jpg\",\"datePublished\":\"2014-11-29T09:00:43+00:00\",\"dateModified\":\"2014-12-03T16:21:36+00:00\",\"author\":{\"@id\":\"https:\/\/www.vivianefreitas.com\/fr\/#\/schema\/person\/da4a30407b47e202130ab7d6faa79cd0\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.vivianefreitas.com\/fr\/2014\/11\/29\/le-jour-que-je-nai-pas-entree-dans-le-godllywood\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.vivianefreitas.com\/fr\/2014\/11\/29\/le-jour-que-je-nai-pas-entree-dans-le-godllywood\/#primaryimage\",\"url\":\"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/11\/nao_entrei_godllywood.jpg\",\"contentUrl\":\"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/11\/nao_entrei_godllywood.jpg\",\"width\":660,\"height\":261},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.vivianefreitas.com\/fr\/#website\",\"url\":\"https:\/\/www.vivianefreitas.com\/fr\/\",\"name\":\"Blog Viviane Freitas\",\"description\":\"Bienvenue dans mon Blog\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.vivianefreitas.com\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.vivianefreitas.com\/fr\/#\/schema\/person\/da4a30407b47e202130ab7d6faa79cd0\",\"name\":\"Viviane Freitas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.vivianefreitas.com\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/718ec4eec1bf41a80d57ad6b6a8be8ab?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/718ec4eec1bf41a80d57ad6b6a8be8ab?s=96&d=mm&r=g\",\"caption\":\"Viviane Freitas\"},\"url\":\"https:\/\/www.vivianefreitas.com\/fr\/author\/viviane-freitas\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Exp\u00e9rience: Le jour que je n\u2019ai pas entr\u00e9e dans le Godllywood - Blog Viviane Freitas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.vivianefreitas.com\/fr\/2014\/11\/29\/le-jour-que-je-nai-pas-entree-dans-le-godllywood\/","og_locale":"fr_FR","og_type":"article","og_title":"Exp\u00e9rience: Le jour que je n\u2019ai pas entr\u00e9e dans le Godllywood - Blog Viviane Freitas","og_url":"https:\/\/www.vivianefreitas.com\/fr\/2014\/11\/29\/le-jour-que-je-nai-pas-entree-dans-le-godllywood\/","og_site_name":"Blog Viviane Freitas","article_published_time":"2014-11-29T09:00:43+00:00","article_modified_time":"2014-12-03T16:21:36+00:00","og_image":[{"width":660,"height":261,"url":"https:\/\/www.vivianefreitas.com\/fr\/files\/2014\/11\/nao_entrei_godllywood.jpg","type":"image\/jpeg"}],"author":"Viviane Freitas","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Viviane Freitas","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.vivianefreitas.com\/fr\/2014\/11\/29\/le-jour-que-je-nai-pas-entree-dans-le-godllywood\/","url":"https:\/\/www.vivianefreitas.com\/fr\/2014\/11\/29\/le-jour-que-je-nai-pas-entree-dans-le-godllywood\/","name":"Exp\u00e9rience: Le jour que je n\u2019ai pas entr\u00e9e dans le Godllywood - Blog Viviane Freitas","isPartOf":{"@id":"https:\/\/www.vivianefreitas.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vivianefreitas.com\/fr\/2014\/11\/29\/le-jour-que-je-nai-pas-entree-dans-le-godllywood\/#primaryimage"},"image":{"@id":"https:\/\/www.vivianefreitas.com\/fr\/2014\/11\/29\/le-jour-que-je-nai-pas-entree-dans-le-godllywood\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/11\/nao_entrei_godllywood.jpg","datePublished":"2014-11-29T09:00:43+00:00","dateModified":"2014-12-03T16:21:36+00:00","author":{"@id":"https:\/\/www.vivianefreitas.com\/fr\/#\/schema\/person\/da4a30407b47e202130ab7d6faa79cd0"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vivianefreitas.com\/fr\/2014\/11\/29\/le-jour-que-je-nai-pas-entree-dans-le-godllywood\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vivianefreitas.com\/fr\/2014\/11\/29\/le-jour-que-je-nai-pas-entree-dans-le-godllywood\/#primaryimage","url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/11\/nao_entrei_godllywood.jpg","contentUrl":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/11\/nao_entrei_godllywood.jpg","width":660,"height":261},{"@type":"WebSite","@id":"https:\/\/www.vivianefreitas.com\/fr\/#website","url":"https:\/\/www.vivianefreitas.com\/fr\/","name":"Blog Viviane Freitas","description":"Bienvenue dans mon Blog","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vivianefreitas.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.vivianefreitas.com\/fr\/#\/schema\/person\/da4a30407b47e202130ab7d6faa79cd0","name":"Viviane Freitas","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vivianefreitas.com\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/718ec4eec1bf41a80d57ad6b6a8be8ab?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/718ec4eec1bf41a80d57ad6b6a8be8ab?s=96&d=mm&r=g","caption":"Viviane Freitas"},"url":"https:\/\/www.vivianefreitas.com\/fr\/author\/viviane-freitas\/"}]}},"jetpack_featured_media_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/11\/nao_entrei_godllywood.jpg","_links":{"self":[{"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/posts\/18861","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/comments?post=18861"}],"version-history":[{"count":2,"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/posts\/18861\/revisions"}],"predecessor-version":[{"id":18864,"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/posts\/18861\/revisions\/18864"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/media\/18862"}],"wp:attachment":[{"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/media?parent=18861"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/categories?post=18861"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/tags?post=18861"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}