{"id":18731,"date":"2014-10-13T12:24:41","date_gmt":"2014-10-13T12:24:41","guid":{"rendered":"http:\/\/www.vivianefreitas.com\/fr\/?p=18731"},"modified":"2014-10-17T12:32:30","modified_gmt":"2014-10-17T12:32:30","slug":"jeunes-jai-peche-et-maintenant-que-faire-2eme-partie","status":"publish","type":"post","link":"https:\/\/www.vivianefreitas.com\/fr\/2014\/10\/13\/jeunes-jai-peche-et-maintenant-que-faire-2eme-partie\/","title":{"rendered":"Jeunes: J&rsquo;ai p\u00e9ch\u00e9! Et maintenant que faire? (2\u00e8me partie)"},"content":{"rendered":"<p><p class=\"intro\">Apr\u00e8s que la personne p\u00e8che, imm\u00e9diatement, l\u2019alliance entre Dieu et la personne est bris\u00e9e.<\/p><br \/>\nLa pratique du p\u00e9ch\u00e9 est une trahison \u00e0 Dieu.<br \/>\n<!--more--><\/p>\n<p>Comment revenir \u00e0 Dieu ce que vous \u00e9tiez\u00a0?  Puisque rien ne semble le m\u00eame, la lecture de la bible ne vous parle plus, le je\u00fbne n\u2019a pas la m\u00eame saveur, la r\u00e9union que nous assistons devient ennuyeux et dans notre pri\u00e8re \u00e0 Dieu le diable accuse tout le temps, vous convaincre que vous n\u2019\u00eates rien et que n\u2019a pas le droit de retour, m\u00eame la mention du nom de Lui.<\/p>\n<p>Il y a une chose que vous avez besoin de savoir\u00a0: <strong>En fait vous ne serez pas comme avant.<\/strong><br \/>\nMais cela n\u2019est pas mauvais. Voyez ce que Dieu a promis\u00a0:<br \/>\n<em><br \/>\n\u00ab\u00a0Si quelqu&rsquo;un est en Christ, il est une nouvelle cr\u00e9ature. Les choses anciennes sont pass\u00e9es; voici, toutes choses sont devenues nouvelles.\u00a0\u00bb<\/em> II Corinthiens 5\u00a0:17<\/p>\n<p>Une fois repentie, arrive \u00e0 maturit\u00e9,<br \/>\nReconnait la mis\u00e9ricorde, le pardon de Dieu et de se sentir plus aim\u00e9,  parce que vous savez qu\u2019Il vous a pardonn\u00e9 et aim\u00e9, m\u00eame sans m\u00e9riter le pardon.<\/p>\n<p>Depuis son retour \u00e0 la pratique des premi\u00e8res \u0153uvres, que sont le fondement du chr\u00e9tien\u00a0: Assister aux r\u00e9unions de l\u2019\u00e9glise,  lire la bible, prier, m\u00e9diter sur Sa volont\u00e9 pour votre vie, je\u00fbner, donner votre offrande, etc. Vous serez en train de reconstruire une nouvelle Alliance.<\/p>\n<p>L\u2019ancienne, que vous avez bris\u00e9e, Dieu n\u2019est pas en elle.<br \/>\nIl vous propose une nouvelle\u00a0! Acceptez-vous\u00a0? <\/p>\n<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La pratique du p\u00e9ch\u00e9 est une trahison \u00e0 Dieu.<\/p>\n","protected":false},"author":4,"featured_media":18732,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-18731","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-jeunes"],"better_featured_image":{"id":18732,"alt_text":"","caption":"","description":"","media_type":"image","media_details":{"width":660,"height":261,"file":"2014\/10\/jovem-pequei2.jpg","sizes":{"thumbnail":{"file":"jovem-pequei2-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/10\/jovem-pequei2-150x150.jpg"},"medium":{"file":"jovem-pequei2-300x118.jpg","width":300,"height":118,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/10\/jovem-pequei2-300x118.jpg"},"blogintro":{"file":"jovem-pequei2-144x100.jpg","width":144,"height":100,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/10\/jovem-pequei2-144x100.jpg"},"onethirdsquare":{"file":"jovem-pequei2-300x261.jpg","width":300,"height":261,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/10\/jovem-pequei2-300x261.jpg"},"oneforthsquare":{"file":"jovem-pequei2-219x219.jpg","width":219,"height":219,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/10\/jovem-pequei2-219x219.jpg"},"onefifthsquare":{"file":"jovem-pequei2-168x168.jpg","width":168,"height":168,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/10\/jovem-pequei2-168x168.jpg"},"onesixthsquare":{"file":"jovem-pequei2-135x135.jpg","width":135,"height":135,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/10\/jovem-pequei2-135x135.jpg"},"onethirdlandscape":{"file":"jovem-pequei2-300x200.jpg","width":300,"height":200,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/10\/jovem-pequei2-300x200.jpg"},"oneforthlandscape":{"file":"jovem-pequei2-219x146.jpg","width":219,"height":146,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/10\/jovem-pequei2-219x146.jpg"},"onefifthlandscape":{"file":"jovem-pequei2-168x112.jpg","width":168,"height":112,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/10\/jovem-pequei2-168x112.jpg"},"onesixthlandscape":{"file":"jovem-pequei2-135x90.jpg","width":135,"height":90,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/10\/jovem-pequei2-135x90.jpg"},"onethirdportrait":{"file":"jovem-pequei2-300x261.jpg","width":300,"height":261,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/10\/jovem-pequei2-300x261.jpg"},"oneforthportrait":{"file":"jovem-pequei2-219x261.jpg","width":219,"height":261,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/10\/jovem-pequei2-219x261.jpg"},"onehalfsquare-inpost":{"file":"jovem-pequei2-305x261.jpg","width":305,"height":261,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/10\/jovem-pequei2-305x261.jpg"},"onethirdsquare-inpost":{"file":"jovem-pequei2-200x200.jpg","width":200,"height":200,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/10\/jovem-pequei2-200x200.jpg"},"oneforthsquare-inpost":{"file":"jovem-pequei2-145x145.jpg","width":145,"height":145,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/10\/jovem-pequei2-145x145.jpg"},"onehalflandscape-inpost":{"file":"jovem-pequei2-305x205.jpg","width":305,"height":205,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/10\/jovem-pequei2-305x205.jpg"},"onethirdlandscape-inpost":{"file":"jovem-pequei2-200x132.jpg","width":200,"height":132,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/10\/jovem-pequei2-200x132.jpg"},"oneforthlandscape-inpost":{"file":"jovem-pequei2-145x96.jpg","width":145,"height":96,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/10\/jovem-pequei2-145x96.jpg"},"onehalfportrait-inpost":{"file":"jovem-pequei2-305x261.jpg","width":305,"height":261,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/10\/jovem-pequei2-305x261.jpg"},"onethirdportrait-inpost":{"file":"jovem-pequei2-200x261.jpg","width":200,"height":261,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/10\/jovem-pequei2-200x261.jpg"},"oneforthportrait-inpost":{"file":"jovem-pequei2-145x193.jpg","width":145,"height":193,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/10\/jovem-pequei2-145x193.jpg"},"pensamentos":{"file":"jovem-pequei2-285x261.jpg","width":285,"height":261,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/10\/jovem-pequei2-285x261.jpg"},"categ":{"file":"jovem-pequei2-210x85.jpg","width":210,"height":85,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/10\/jovem-pequei2-210x85.jpg"}},"image_meta":{"aperture":0,"credit":"","camera":"","caption":"","created_timestamp":0,"copyright":"Alexander Trinitatov - Fotolia","focal_length":0,"iso":0,"shutter_speed":0,"title":""}},"post":18731,"source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/10\/jovem-pequei2.jpg"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Jeunes: J&#039;ai p\u00e9ch\u00e9! Et maintenant que faire? (2\u00e8me partie) - Blog Viviane Freitas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.vivianefreitas.com\/fr\/2014\/10\/13\/jeunes-jai-peche-et-maintenant-que-faire-2eme-partie\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jeunes: J&#039;ai p\u00e9ch\u00e9! Et maintenant que faire? (2\u00e8me partie) - Blog Viviane Freitas\" \/>\n<meta property=\"og:description\" content=\"La pratique du p\u00e9ch\u00e9 est une trahison \u00e0 Dieu.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vivianefreitas.com\/fr\/2014\/10\/13\/jeunes-jai-peche-et-maintenant-que-faire-2eme-partie\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Viviane Freitas\" \/>\n<meta property=\"article:published_time\" content=\"2014-10-13T12:24:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2014-10-17T12:32:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vivianefreitas.com\/fr\/files\/2014\/10\/jovem-pequei2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"660\" \/>\n\t<meta property=\"og:image:height\" content=\"261\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Viviane Freitas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Viviane Freitas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.vivianefreitas.com\/fr\/2014\/10\/13\/jeunes-jai-peche-et-maintenant-que-faire-2eme-partie\/\",\"url\":\"https:\/\/www.vivianefreitas.com\/fr\/2014\/10\/13\/jeunes-jai-peche-et-maintenant-que-faire-2eme-partie\/\",\"name\":\"Jeunes: J'ai p\u00e9ch\u00e9! Et maintenant que faire? (2\u00e8me partie) - Blog Viviane Freitas\",\"isPartOf\":{\"@id\":\"https:\/\/www.vivianefreitas.com\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.vivianefreitas.com\/fr\/2014\/10\/13\/jeunes-jai-peche-et-maintenant-que-faire-2eme-partie\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.vivianefreitas.com\/fr\/2014\/10\/13\/jeunes-jai-peche-et-maintenant-que-faire-2eme-partie\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/10\/jovem-pequei2.jpg\",\"datePublished\":\"2014-10-13T12:24:41+00:00\",\"dateModified\":\"2014-10-17T12:32:30+00:00\",\"author\":{\"@id\":\"https:\/\/www.vivianefreitas.com\/fr\/#\/schema\/person\/da4a30407b47e202130ab7d6faa79cd0\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.vivianefreitas.com\/fr\/2014\/10\/13\/jeunes-jai-peche-et-maintenant-que-faire-2eme-partie\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.vivianefreitas.com\/fr\/2014\/10\/13\/jeunes-jai-peche-et-maintenant-que-faire-2eme-partie\/#primaryimage\",\"url\":\"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/10\/jovem-pequei2.jpg\",\"contentUrl\":\"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/10\/jovem-pequei2.jpg\",\"width\":660,\"height\":261},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.vivianefreitas.com\/fr\/#website\",\"url\":\"https:\/\/www.vivianefreitas.com\/fr\/\",\"name\":\"Blog Viviane Freitas\",\"description\":\"Bienvenue dans mon Blog\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.vivianefreitas.com\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.vivianefreitas.com\/fr\/#\/schema\/person\/da4a30407b47e202130ab7d6faa79cd0\",\"name\":\"Viviane Freitas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.vivianefreitas.com\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/718ec4eec1bf41a80d57ad6b6a8be8ab?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/718ec4eec1bf41a80d57ad6b6a8be8ab?s=96&d=mm&r=g\",\"caption\":\"Viviane Freitas\"},\"url\":\"https:\/\/www.vivianefreitas.com\/fr\/author\/viviane-freitas\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jeunes: J'ai p\u00e9ch\u00e9! Et maintenant que faire? (2\u00e8me partie) - Blog Viviane Freitas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.vivianefreitas.com\/fr\/2014\/10\/13\/jeunes-jai-peche-et-maintenant-que-faire-2eme-partie\/","og_locale":"fr_FR","og_type":"article","og_title":"Jeunes: J'ai p\u00e9ch\u00e9! Et maintenant que faire? (2\u00e8me partie) - Blog Viviane Freitas","og_description":"La pratique du p\u00e9ch\u00e9 est une trahison \u00e0 Dieu.","og_url":"https:\/\/www.vivianefreitas.com\/fr\/2014\/10\/13\/jeunes-jai-peche-et-maintenant-que-faire-2eme-partie\/","og_site_name":"Blog Viviane Freitas","article_published_time":"2014-10-13T12:24:41+00:00","article_modified_time":"2014-10-17T12:32:30+00:00","og_image":[{"width":660,"height":261,"url":"https:\/\/www.vivianefreitas.com\/fr\/files\/2014\/10\/jovem-pequei2.jpg","type":"image\/jpeg"}],"author":"Viviane Freitas","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Viviane Freitas","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.vivianefreitas.com\/fr\/2014\/10\/13\/jeunes-jai-peche-et-maintenant-que-faire-2eme-partie\/","url":"https:\/\/www.vivianefreitas.com\/fr\/2014\/10\/13\/jeunes-jai-peche-et-maintenant-que-faire-2eme-partie\/","name":"Jeunes: J'ai p\u00e9ch\u00e9! Et maintenant que faire? (2\u00e8me partie) - Blog Viviane Freitas","isPartOf":{"@id":"https:\/\/www.vivianefreitas.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vivianefreitas.com\/fr\/2014\/10\/13\/jeunes-jai-peche-et-maintenant-que-faire-2eme-partie\/#primaryimage"},"image":{"@id":"https:\/\/www.vivianefreitas.com\/fr\/2014\/10\/13\/jeunes-jai-peche-et-maintenant-que-faire-2eme-partie\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/10\/jovem-pequei2.jpg","datePublished":"2014-10-13T12:24:41+00:00","dateModified":"2014-10-17T12:32:30+00:00","author":{"@id":"https:\/\/www.vivianefreitas.com\/fr\/#\/schema\/person\/da4a30407b47e202130ab7d6faa79cd0"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vivianefreitas.com\/fr\/2014\/10\/13\/jeunes-jai-peche-et-maintenant-que-faire-2eme-partie\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vivianefreitas.com\/fr\/2014\/10\/13\/jeunes-jai-peche-et-maintenant-que-faire-2eme-partie\/#primaryimage","url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/10\/jovem-pequei2.jpg","contentUrl":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/10\/jovem-pequei2.jpg","width":660,"height":261},{"@type":"WebSite","@id":"https:\/\/www.vivianefreitas.com\/fr\/#website","url":"https:\/\/www.vivianefreitas.com\/fr\/","name":"Blog Viviane Freitas","description":"Bienvenue dans mon Blog","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vivianefreitas.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.vivianefreitas.com\/fr\/#\/schema\/person\/da4a30407b47e202130ab7d6faa79cd0","name":"Viviane Freitas","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vivianefreitas.com\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/718ec4eec1bf41a80d57ad6b6a8be8ab?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/718ec4eec1bf41a80d57ad6b6a8be8ab?s=96&d=mm&r=g","caption":"Viviane Freitas"},"url":"https:\/\/www.vivianefreitas.com\/fr\/author\/viviane-freitas\/"}]}},"jetpack_featured_media_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/10\/jovem-pequei2.jpg","_links":{"self":[{"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/posts\/18731","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/comments?post=18731"}],"version-history":[{"count":2,"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/posts\/18731\/revisions"}],"predecessor-version":[{"id":18734,"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/posts\/18731\/revisions\/18734"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/media\/18732"}],"wp:attachment":[{"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/media?parent=18731"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/categories?post=18731"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/tags?post=18731"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}