{"id":18378,"date":"2014-07-09T14:38:24","date_gmt":"2014-07-09T14:38:24","guid":{"rendered":"http:\/\/www.vivianefreitas.com\/fr\/?p=18378"},"modified":"2014-07-10T14:51:18","modified_gmt":"2014-07-10T14:51:18","slug":"30eme-jour-que-fait-jesus-lorsque-lon-vient-a-lui","status":"publish","type":"post","link":"https:\/\/www.vivianefreitas.com\/fr\/2014\/07\/09\/30eme-jour-que-fait-jesus-lorsque-lon-vient-a-lui\/","title":{"rendered":"30\u00e8me jour &#8211; Que fait J\u00e9sus, lorsque l\u2019on vient \u00e0 Lui"},"content":{"rendered":"<p>\u00abTous ceux que le P\u00e8re me donne viendront \u00e0 moi, et je ne mettrai pas dehors celui qui vient \u00e0 moi; car je suis descendu du ciel pour faire, non ma volont\u00e9, mais la volont\u00e9 de celui qui m&rsquo;a envoy\u00e9. Or, la volont\u00e9 de celui qui m&rsquo;a envoy\u00e9, c&rsquo;est que je ne perde rien de tout ce qu&rsquo;il m&rsquo;a donn\u00e9, mais que je le ressuscite au dernier jour.\u00bb (Jean 6:37-39)<br \/>\n<!--more--><\/p>\n<p>Quelqu\u2019un va \u00e0 Dieu, pas simplement lorsqu\u2019il dit qu&rsquo;il veut J\u00e9sus, ou parce qu\u2019il va \u00e0 l&rsquo;Eglise, donne ses d\u00eemes et ses offrandes. Mais celui qui Le d\u00e9sire vraiment, va \u00e0 Lui. Comment?<\/p>\n<p>Par exemple: quand nous nous dirigerons vers quelqu&rsquo;un, dispos\u00e9 \u00e0 nous ouvrir, nous d\u00e9pouiller de nous-m\u00eames, nous sommes en train de montrer une confiance et celui qui proc\u00e8de ainsi, par rapport \u00e0 Dieu, est celui que le P\u00e8re a donn\u00e9 au Seigneur J\u00e9sus.<\/p>\n<p>M\u00eame s\u2019il a eu un pass\u00e9 terrible, qui ne lui sort pas l\u2019esprit et pour plus qu\u2019il ne se pardonne pas, d\u00e8s l&rsquo;instant o\u00f9 il va au Seigneur J\u00e9sus, il cesse de se culpabiliser. Il a honte de ses erreurs, les hait, parce que la haine contre le p\u00e9ch\u00e9, c&rsquo;est ce qui le fait lutter contre son \u00e9tat.<\/p>\n<p>En revanche, s\u2019il se sent faible, n\u2019a pas de forces, se condamne et ne pense pas \u00eatre digne de parler avec Dieu de cette fa\u00e7on, il ne vient pas au Seigneur J\u00e9sus, parce que s\u2019il le faisait, il croirait \u00e0 ce qu&rsquo;Il a fait pour lui, sur la Croix. Cette culpabilit\u00e9 et ces accusations, qu\u2019il ne vaut rien ou que cela n\u2019avance \u00e0 rien, c\u2019est la voix du diable, parce que, au moment o\u00f9 il croit, il va \u00e0 Dieu, expose tout ce qui est \u00e0 l&rsquo;int\u00e9rieur de son c\u0153ur, est sinc\u00e8re envers Lui. Cela le m\u00e8ne \u00e0 avoir un objectif \u00e0 atteindre; un but en ce qui concerne sa vie avec Dieu.<\/p>\n<p><em>\u00abTous ceux que le P\u00e8re me donne viendront \u00e0 moi, et je ne mettrai pas dehors celui qui vient \u00e0 moi\u00bb<\/em><\/p>\n<p>Le Seigneur J\u00e9sus, ne vous rejette pas! Peu importe ce qui est arriv\u00e9 dans votre pass\u00e9, ou m\u00eame encore hier&#8230; Il ne vous abandonne pas!<\/p>\n<p><em>\u00abOr, la volont\u00e9 de celui qui m&rsquo;a envoy\u00e9, c&rsquo;est que je ne perde rien de tout ce qu&rsquo;il m&rsquo;a donn\u00e9, mais que je le ressuscite au dernier jour.\u00bb<\/em><\/p>\n<p>Vous, qui vous condamnez pour vos \u00e9checs, vos imperfections et vos fautes, le Seigneur J\u00e9sus ne veut pas vous perdre! Mais vous \u00eates confront\u00e9 \u00e0 des voix: celle du diable, de Dieu et celle de votre propre volont\u00e9. Vers qui allez-vous vous incliner et laquelle allez-vous \u00e9couter?!<\/p>\n<p>Lorsque vous \u00e9coutez la voix de Dieu, vous avez la force de r\u00e9soudre ce qui est \u00e0 l&rsquo;int\u00e9rieur de vous, il n\u2019y a pas de condamnation!<\/p>\n<p>Lorsque je me condamnais, il y n&rsquo;avait aucune solution, sauf les larmes et la foi \u00e9motive. Sortez de cette prostration, maintenant! Parce que Dieu n&rsquo;a pas envoy\u00e9 Son Fils pour vous condamner. Le Seigneur J\u00e9sus a d\u00e9j\u00e0 pay\u00e9 le prix pour d\u00e9livrer du p\u00e9ch\u00e9. Il suffit d\u2019assumer votre p\u00e9ch\u00e9, ne le commettez plus; r\u00e9solvez le probl\u00e8me et luttez contre les pens\u00e9es que le diable met dans votre esprit, que vous n\u2019allez pas r\u00e9ussir, que vous \u00eates d\u00e9j\u00e0 au 30\u00e8me jour; qu\u2019il ne reste plus que 10 jours et, jusqu&rsquo;\u00e0 pr\u00e9sent, vous n&rsquo;avez pas r\u00e9ussi&#8230; Si vous entendez sa voix, vous \u00eates en train de le servir et vous ne pouvez pas donner ce droit au diable!<\/p>\n<p>Vous avez le choix: le Seigneur J\u00e9sus veut vous arracher de cette situation, mais vous devez croire en Lui.<\/p>\n<p><em>\u00abOr, la volont\u00e9 de celui qui m&rsquo;a envoy\u00e9, c&rsquo;est que je ne perde rien de tout ce qu&rsquo;il m&rsquo;a donn\u00e9, mais que je le ressuscite au dernier jour.\u00bb<\/em><\/p>\n<p>Dieu va vous ressusciter, vous faire sortir de cette situation. Sa volont\u00e9 c\u2019est que vous veniez et croyez, pour poss\u00e9der la vie \u00e9ternelle.<\/p>\n<p>Il n&rsquo;y a aucun \u00eatre humain \u2013 si ce n\u2019est le Seigneur J\u00e9sus, quand Il \u00e9tait parmi nous &#8211; qui n&rsquo;ait pas eu de p\u00e9ch\u00e9. Tout le monde, sans exception, a p\u00e9ch\u00e9 et tous ont besoin d&rsquo;\u00eatre sauv\u00e9s. Et nous ne sommes pas sauv\u00e9s, par nos m\u00e9rites, ou pour ce que nous avons de bon, parce qu&rsquo;il n&rsquo;y a rien de bon en nous.<\/p>\n<p>Nous sommes sauv\u00e9s par la foi, par la croyance, pour le fait de se donner! Lorsque vous vous donnez, vous vous jetez dans les bras de Dieu, sans crainte; Il n&rsquo;y a pas de diable, de condamnation et de pens\u00e9es n\u00e9gatives, rien ne peut vous emp\u00eacher de vous lancer. Vous devez uniquement croire et c\u2019est cela qui vous rend libre!<\/p>\n<p>Restez dans la foi et ne laissez pas le diable vous d\u00e9vier de votre objectif. Vous le pouvez, je le peux.<\/p>\n<p>J&rsquo;ai \u00e9t\u00e9 restitu\u00e9e pour l&rsquo;amour du Seigneur J\u00e9sus et par Sa mis\u00e9ricorde envers moi.<\/p>\n<p>Ce probl\u00e8me, que vous voyez et contre lequel vous luttez, n&rsquo;est pas pour vous enfoncer, mais pour r\u00e9soudre votre situation, en pla\u00e7ant le diable sous vos pieds et en le \u00abmassacrant\u00bb, par le biais de votre croyance, de vous donner \u00e0 Lui et de votre sinc\u00e9rit\u00e9.<\/p>\n<p>Et qui n&rsquo;est pas en mesure d&rsquo;\u00eatre sinc\u00e8re et de se lancer?!<\/p>\n<p>Tout le monde!!<\/p>\n<p>Si vous avez quelque chose \u00e0 dire, \u00e9crivez, je veux le savoir. Demain, nous serons de retour.<\/p>\n\n","protected":false},"excerpt":{"rendered":"<p>\u00abTous ceux que le P\u00e8re me donne viendront \u00e0 moi, et je ne mettrai pas dehors celui qui vient \u00e0 moi; car je suis descendu du ciel pour faire, non ma volont\u00e9, mais la volont\u00e9 de celui qui m&rsquo;a envoy\u00e9. Or, la volont\u00e9 de celui qui m&rsquo;a envoy\u00e9, c&rsquo;est que je ne perde rien de<\/p>\n<p class=\"bold\"><a href=\"https:\/\/www.vivianefreitas.com\/fr\/2014\/07\/09\/30eme-jour-que-fait-jesus-lorsque-lon-vient-a-lui\/\">En savoir plus<\/a><\/p>\n","protected":false},"author":4,"featured_media":18379,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[21,19],"tags":[],"class_list":["post-18378","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-40-jours-etre-un-avec-lui","category-reflexion"],"better_featured_image":{"id":18379,"alt_text":"","caption":"","description":"","media_type":"image","media_details":{"width":660,"height":261,"file":"2014\/07\/jj30.jpg","sizes":{"thumbnail":{"file":"jj30-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/07\/jj30-150x150.jpg"},"medium":{"file":"jj30-300x118.jpg","width":300,"height":118,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/07\/jj30-300x118.jpg"},"blogintro":{"file":"jj30-144x100.jpg","width":144,"height":100,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/07\/jj30-144x100.jpg"},"onethirdsquare":{"file":"jj30-300x261.jpg","width":300,"height":261,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/07\/jj30-300x261.jpg"},"oneforthsquare":{"file":"jj30-219x219.jpg","width":219,"height":219,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/07\/jj30-219x219.jpg"},"onefifthsquare":{"file":"jj30-168x168.jpg","width":168,"height":168,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/07\/jj30-168x168.jpg"},"onesixthsquare":{"file":"jj30-135x135.jpg","width":135,"height":135,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/07\/jj30-135x135.jpg"},"onethirdlandscape":{"file":"jj30-300x200.jpg","width":300,"height":200,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/07\/jj30-300x200.jpg"},"oneforthlandscape":{"file":"jj30-219x146.jpg","width":219,"height":146,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/07\/jj30-219x146.jpg"},"onefifthlandscape":{"file":"jj30-168x112.jpg","width":168,"height":112,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/07\/jj30-168x112.jpg"},"onesixthlandscape":{"file":"jj30-135x90.jpg","width":135,"height":90,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/07\/jj30-135x90.jpg"},"onethirdportrait":{"file":"jj30-300x261.jpg","width":300,"height":261,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/07\/jj30-300x261.jpg"},"oneforthportrait":{"file":"jj30-219x261.jpg","width":219,"height":261,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/07\/jj30-219x261.jpg"},"onehalfsquare-inpost":{"file":"jj30-305x261.jpg","width":305,"height":261,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/07\/jj30-305x261.jpg"},"onethirdsquare-inpost":{"file":"jj30-200x200.jpg","width":200,"height":200,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/07\/jj30-200x200.jpg"},"oneforthsquare-inpost":{"file":"jj30-145x145.jpg","width":145,"height":145,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/07\/jj30-145x145.jpg"},"onehalflandscape-inpost":{"file":"jj30-305x205.jpg","width":305,"height":205,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/07\/jj30-305x205.jpg"},"onethirdlandscape-inpost":{"file":"jj30-200x132.jpg","width":200,"height":132,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/07\/jj30-200x132.jpg"},"oneforthlandscape-inpost":{"file":"jj30-145x96.jpg","width":145,"height":96,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/07\/jj30-145x96.jpg"},"onehalfportrait-inpost":{"file":"jj30-305x261.jpg","width":305,"height":261,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/07\/jj30-305x261.jpg"},"onethirdportrait-inpost":{"file":"jj30-200x261.jpg","width":200,"height":261,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/07\/jj30-200x261.jpg"},"oneforthportrait-inpost":{"file":"jj30-145x193.jpg","width":145,"height":193,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/07\/jj30-145x193.jpg"},"pensamentos":{"file":"jj30-285x261.jpg","width":285,"height":261,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/07\/jj30-285x261.jpg"},"categ":{"file":"jj30-210x85.jpg","width":210,"height":85,"mime-type":"image\/jpeg","source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/07\/jj30-210x85.jpg"}},"image_meta":{"aperture":0,"credit":"","camera":"","caption":"","created_timestamp":0,"copyright":"Sunny studio - Fotolia","focal_length":0,"iso":0,"shutter_speed":0,"title":""}},"post":18378,"source_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/07\/jj30.jpg"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>30\u00e8me jour - Que fait J\u00e9sus, lorsque l\u2019on vient \u00e0 Lui - Blog Viviane Freitas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.vivianefreitas.com\/fr\/2014\/07\/09\/30eme-jour-que-fait-jesus-lorsque-lon-vient-a-lui\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"30\u00e8me jour - Que fait J\u00e9sus, lorsque l\u2019on vient \u00e0 Lui - Blog Viviane Freitas\" \/>\n<meta property=\"og:description\" content=\"\u00abTous ceux que le P\u00e8re me donne viendront \u00e0 moi, et je ne mettrai pas dehors celui qui vient \u00e0 moi; car je suis descendu du ciel pour faire, non ma volont\u00e9, mais la volont\u00e9 de celui qui m&rsquo;a envoy\u00e9. Or, la volont\u00e9 de celui qui m&rsquo;a envoy\u00e9, c&rsquo;est que je ne perde rien deEn savoir plus\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vivianefreitas.com\/fr\/2014\/07\/09\/30eme-jour-que-fait-jesus-lorsque-lon-vient-a-lui\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Viviane Freitas\" \/>\n<meta property=\"article:published_time\" content=\"2014-07-09T14:38:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2014-07-10T14:51:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vivianefreitas.com\/fr\/files\/2014\/07\/jj30.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"660\" \/>\n\t<meta property=\"og:image:height\" content=\"261\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Viviane Freitas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Viviane Freitas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.vivianefreitas.com\/fr\/2014\/07\/09\/30eme-jour-que-fait-jesus-lorsque-lon-vient-a-lui\/\",\"url\":\"https:\/\/www.vivianefreitas.com\/fr\/2014\/07\/09\/30eme-jour-que-fait-jesus-lorsque-lon-vient-a-lui\/\",\"name\":\"30\u00e8me jour - Que fait J\u00e9sus, lorsque l\u2019on vient \u00e0 Lui - Blog Viviane Freitas\",\"isPartOf\":{\"@id\":\"https:\/\/www.vivianefreitas.com\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.vivianefreitas.com\/fr\/2014\/07\/09\/30eme-jour-que-fait-jesus-lorsque-lon-vient-a-lui\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.vivianefreitas.com\/fr\/2014\/07\/09\/30eme-jour-que-fait-jesus-lorsque-lon-vient-a-lui\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/07\/jj30.jpg\",\"datePublished\":\"2014-07-09T14:38:24+00:00\",\"dateModified\":\"2014-07-10T14:51:18+00:00\",\"author\":{\"@id\":\"https:\/\/www.vivianefreitas.com\/fr\/#\/schema\/person\/da4a30407b47e202130ab7d6faa79cd0\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.vivianefreitas.com\/fr\/2014\/07\/09\/30eme-jour-que-fait-jesus-lorsque-lon-vient-a-lui\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.vivianefreitas.com\/fr\/2014\/07\/09\/30eme-jour-que-fait-jesus-lorsque-lon-vient-a-lui\/#primaryimage\",\"url\":\"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/07\/jj30.jpg\",\"contentUrl\":\"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/07\/jj30.jpg\",\"width\":660,\"height\":261},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.vivianefreitas.com\/fr\/#website\",\"url\":\"https:\/\/www.vivianefreitas.com\/fr\/\",\"name\":\"Blog Viviane Freitas\",\"description\":\"Bienvenue dans mon Blog\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.vivianefreitas.com\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.vivianefreitas.com\/fr\/#\/schema\/person\/da4a30407b47e202130ab7d6faa79cd0\",\"name\":\"Viviane Freitas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.vivianefreitas.com\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/718ec4eec1bf41a80d57ad6b6a8be8ab?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/718ec4eec1bf41a80d57ad6b6a8be8ab?s=96&d=mm&r=g\",\"caption\":\"Viviane Freitas\"},\"url\":\"https:\/\/www.vivianefreitas.com\/fr\/author\/viviane-freitas\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"30\u00e8me jour - Que fait J\u00e9sus, lorsque l\u2019on vient \u00e0 Lui - Blog Viviane Freitas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.vivianefreitas.com\/fr\/2014\/07\/09\/30eme-jour-que-fait-jesus-lorsque-lon-vient-a-lui\/","og_locale":"fr_FR","og_type":"article","og_title":"30\u00e8me jour - Que fait J\u00e9sus, lorsque l\u2019on vient \u00e0 Lui - Blog Viviane Freitas","og_description":"\u00abTous ceux que le P\u00e8re me donne viendront \u00e0 moi, et je ne mettrai pas dehors celui qui vient \u00e0 moi; car je suis descendu du ciel pour faire, non ma volont\u00e9, mais la volont\u00e9 de celui qui m&rsquo;a envoy\u00e9. Or, la volont\u00e9 de celui qui m&rsquo;a envoy\u00e9, c&rsquo;est que je ne perde rien deEn savoir plus","og_url":"https:\/\/www.vivianefreitas.com\/fr\/2014\/07\/09\/30eme-jour-que-fait-jesus-lorsque-lon-vient-a-lui\/","og_site_name":"Blog Viviane Freitas","article_published_time":"2014-07-09T14:38:24+00:00","article_modified_time":"2014-07-10T14:51:18+00:00","og_image":[{"width":660,"height":261,"url":"https:\/\/www.vivianefreitas.com\/fr\/files\/2014\/07\/jj30.jpg","type":"image\/jpeg"}],"author":"Viviane Freitas","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Viviane Freitas","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.vivianefreitas.com\/fr\/2014\/07\/09\/30eme-jour-que-fait-jesus-lorsque-lon-vient-a-lui\/","url":"https:\/\/www.vivianefreitas.com\/fr\/2014\/07\/09\/30eme-jour-que-fait-jesus-lorsque-lon-vient-a-lui\/","name":"30\u00e8me jour - Que fait J\u00e9sus, lorsque l\u2019on vient \u00e0 Lui - Blog Viviane Freitas","isPartOf":{"@id":"https:\/\/www.vivianefreitas.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vivianefreitas.com\/fr\/2014\/07\/09\/30eme-jour-que-fait-jesus-lorsque-lon-vient-a-lui\/#primaryimage"},"image":{"@id":"https:\/\/www.vivianefreitas.com\/fr\/2014\/07\/09\/30eme-jour-que-fait-jesus-lorsque-lon-vient-a-lui\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/07\/jj30.jpg","datePublished":"2014-07-09T14:38:24+00:00","dateModified":"2014-07-10T14:51:18+00:00","author":{"@id":"https:\/\/www.vivianefreitas.com\/fr\/#\/schema\/person\/da4a30407b47e202130ab7d6faa79cd0"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vivianefreitas.com\/fr\/2014\/07\/09\/30eme-jour-que-fait-jesus-lorsque-lon-vient-a-lui\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vivianefreitas.com\/fr\/2014\/07\/09\/30eme-jour-que-fait-jesus-lorsque-lon-vient-a-lui\/#primaryimage","url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/07\/jj30.jpg","contentUrl":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/07\/jj30.jpg","width":660,"height":261},{"@type":"WebSite","@id":"https:\/\/www.vivianefreitas.com\/fr\/#website","url":"https:\/\/www.vivianefreitas.com\/fr\/","name":"Blog Viviane Freitas","description":"Bienvenue dans mon Blog","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vivianefreitas.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.vivianefreitas.com\/fr\/#\/schema\/person\/da4a30407b47e202130ab7d6faa79cd0","name":"Viviane Freitas","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vivianefreitas.com\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/718ec4eec1bf41a80d57ad6b6a8be8ab?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/718ec4eec1bf41a80d57ad6b6a8be8ab?s=96&d=mm&r=g","caption":"Viviane Freitas"},"url":"https:\/\/www.vivianefreitas.com\/fr\/author\/viviane-freitas\/"}]}},"jetpack_featured_media_url":"https:\/\/www.vivianefreitas.com\/fr\/wp-content\/blogs.dir\/3\/files\/2014\/07\/jj30.jpg","_links":{"self":[{"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/posts\/18378","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/comments?post=18378"}],"version-history":[{"count":1,"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/posts\/18378\/revisions"}],"predecessor-version":[{"id":18380,"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/posts\/18378\/revisions\/18380"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/media\/18379"}],"wp:attachment":[{"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/media?parent=18378"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/categories?post=18378"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vivianefreitas.com\/fr\/wp-json\/wp\/v2\/tags?post=18378"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}